
  
{"id":5495,"date":"2020-06-30T13:16:39","date_gmt":"2020-06-30T11:16:39","guid":{"rendered":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2020\/06\/pexels-photo-1936299-1.jpg"},"modified":"2020-06-30T13:16:48","modified_gmt":"2020-06-30T11:16:48","slug":"pexels-photo-1936299-2","status":"inherit","type":"attachment","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/pexels-photo-1936299-2\/","title":{"rendered":"pexels-photo-1936299"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":""},"class_list":["post-5495","attachment","type-attachment","status-inherit","entry","has-post-thumbnail"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Efor\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/pexels-photo-1936299-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"La Innovaci\u00f3n Necesaria | Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"pexels-photo-1936299 | La Innovaci\u00f3n Necesaria\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/pexels-photo-1936299-2\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-06-30T11:16:39+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-06-30T11:16:48+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"pexels-photo-1936299 | La Innovaci\u00f3n Necesaria\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/pexels-photo-1936299-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/pexels-photo-1936299-2\\\/#listItem\",\"name\":\"pexels-photo-1936299\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/pexels-photo-1936299-2\\\/#listItem\",\"position\":2,\"name\":\"pexels-photo-1936299\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria#listItem\",\"name\":\"Inicio\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/pexels-photo-1936299-2\\\/#itempage\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/pexels-photo-1936299-2\\\/\",\"name\":\"pexels-photo-1936299 | La Innovaci\\u00f3n Necesaria\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/pexels-photo-1936299-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/efor\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/efor\\\/#author\"},\"datePublished\":\"2020-06-30T13:16:39+02:00\",\"dateModified\":\"2020-06-30T13:16:48+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#organization\",\"name\":\"La Innovaci\\u00f3n Necesaria\",\"description\":\"Blog sobre tecnolog\\u00eda, business intelligence, marketing digital, cloud y seguridad.\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-integra-blanco.svg\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/pexels-photo-1936299-2\\\/#organizationLogo\",\"width\":165,\"height\":38},\"image\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/pexels-photo-1936299-2\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/efor\\\/#author\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/efor\\\/\",\"name\":\"Efor\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/pexels-photo-1936299-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/46643c3e298b59250b98497f94070ef639f56b610a0ce6825a79e61d8a267542?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Efor\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#website\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/\",\"name\":\"La Innovaci\\u00f3n Necesaria\",\"description\":\"Blog sobre tecnolog\\u00eda, business intelligence, marketing digital, cloud y seguridad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"pexels-photo-1936299 | La Innovaci\u00f3n Necesaria","description":"","canonical_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/pexels-photo-1936299-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/pexels-photo-1936299-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria#listItem","position":1,"name":"Inicio","item":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria","nextItem":{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/pexels-photo-1936299-2\/#listItem","name":"pexels-photo-1936299"}},{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/pexels-photo-1936299-2\/#listItem","position":2,"name":"pexels-photo-1936299","previousItem":{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria#listItem","name":"Inicio"}}]},{"@type":"ItemPage","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/pexels-photo-1936299-2\/#itempage","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/pexels-photo-1936299-2\/","name":"pexels-photo-1936299 | La Innovaci\u00f3n Necesaria","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#website"},"breadcrumb":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/pexels-photo-1936299-2\/#breadcrumblist"},"author":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/efor\/#author"},"creator":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/efor\/#author"},"datePublished":"2020-06-30T13:16:39+02:00","dateModified":"2020-06-30T13:16:48+02:00"},{"@type":"Organization","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#organization","name":"La Innovaci\u00f3n Necesaria","description":"Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/","logo":{"@type":"ImageObject","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/pexels-photo-1936299-2\/#organizationLogo","width":165,"height":38},"image":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/pexels-photo-1936299-2\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/efor\/#author","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/efor\/","name":"Efor","image":{"@type":"ImageObject","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/pexels-photo-1936299-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/46643c3e298b59250b98497f94070ef639f56b610a0ce6825a79e61d8a267542?s=96&d=mm&r=g","width":96,"height":96,"caption":"Efor"}},{"@type":"WebSite","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#website","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/","name":"La Innovaci\u00f3n Necesaria","description":"Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#organization"}}]},"og:locale":"es_ES","og:site_name":"La Innovaci\u00f3n Necesaria | Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.","og:type":"article","og:title":"pexels-photo-1936299 | La Innovaci\u00f3n Necesaria","og:url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/pexels-photo-1936299-2\/","og:image":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg","og:image:secure_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg","article:published_time":"2020-06-30T11:16:39+00:00","article:modified_time":"2020-06-30T11:16:48+00:00","twitter:card":"summary","twitter:title":"pexels-photo-1936299 | La Innovaci\u00f3n Necesaria","twitter:image":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg"},"aioseo_meta_data":{"post_id":"5495","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-09-28 14:45:51","updated":"2022-10-10 02:06:04","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tpexels-photo-1936299\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria"},{"label":"pexels-photo-1936299","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/pexels-photo-1936299-2\/"}],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2020\/06\/pexels-photo-1936299-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"116\" src=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2020\/06\/pexels-photo-1936299-1-720x279.jpg\" class=\"attachment-medium size-medium\" alt=\"Inteligencia Artificial\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Inteligencia Artificial","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1880,"height":279,"file":"2020\/06\/pexels-photo-1936299-1.jpg","sizes":{"medium":{"file":"pexels-photo-1936299-1-720x279.jpg","width":720,"height":279,"mime_type":"image\/jpeg","source_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2020\/06\/pexels-photo-1936299-1-720x279.jpg"},"large":{"file":"pexels-photo-1936299-1-1170x279.jpg","width":1170,"height":279,"mime_type":"image\/jpeg","source_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2020\/06\/pexels-photo-1936299-1-1170x279.jpg"},"thumbnail":{"file":"pexels-photo-1936299-1-80x80.jpg","width":80,"height":80,"mime_type":"image\/jpeg","source_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2020\/06\/pexels-photo-1936299-1-80x80.jpg"},"medium_large":{"file":"pexels-photo-1936299-1-768x114.jpg","width":768,"height":114,"mime_type":"image\/jpeg","source_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2020\/06\/pexels-photo-1936299-1-768x114.jpg"},"wysija-newsletters-max":{"file":"pexels-photo-1936299-1-600x89.jpg","width":600,"height":89,"mime_type":"image\/jpeg","source_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2020\/06\/pexels-photo-1936299-1-600x89.jpg"},"1536x1536":{"file":"pexels-photo-1936299-1-1536x228.jpg","width":1536,"height":228,"mime_type":"image\/jpeg","source_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2020\/06\/pexels-photo-1936299-1-1536x228.jpg"},"bloom_image":{"file":"pexels-photo-1936299-1-610x91.jpg","width":610,"height":91,"mime_type":"image\/jpeg","source_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2020\/06\/pexels-photo-1936299-1-610x91.jpg"},"single-large":{"file":"pexels-photo-1936299-1-980x279.jpg","width":980,"height":279,"mime_type":"image\/jpeg","source_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2020\/06\/pexels-photo-1936299-1-980x279.jpg"},"small":{"file":"pexels-photo-1936299-1-340x213.jpg","width":340,"height":213,"mime_type":"image\/jpeg","source_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2020\/06\/pexels-photo-1936299-1-340x213.jpg"},"thumbnail-large":{"file":"pexels-photo-1936299-1-160x160.jpg","width":160,"height":160,"mime_type":"image\/jpeg","source_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2020\/06\/pexels-photo-1936299-1-160x160.jpg"},"full-width-image":{"file":"pexels-photo-1936299-1-1400x279.jpg","width":1400,"height":279,"mime_type":"image\/jpeg","source_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2020\/06\/pexels-photo-1936299-1-1400x279.jpg"},"full":{"file":"pexels-photo-1936299-1.jpg","width":1880,"height":279,"mime_type":"image\/jpeg","source_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2020\/06\/pexels-photo-1936299-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2020\/06\/pexels-photo-1936299-1.jpg","filename":"pexels-photo-1936299-1.jpg","filesize":382177,"_links":{"self":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media\/5495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/comments?post=5495"}]}}