
  
{"id":2072,"date":"2016-12-20T15:26:10","date_gmt":"2016-12-20T14:26:10","guid":{"rendered":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/?p=2072"},"modified":"2023-12-26T17:38:14","modified_gmt":"2023-12-26T16:38:14","slug":"las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii","status":"publish","type":"post","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/","title":{"rendered":"Las personas, centro de la estrategia de las organizaciones (Parte II)"},"content":{"rendered":"<p>En este segundo art\u00edculo, os presentamos una propuesta de c\u00f3mo, desde las organizaciones, podemos desplegar y facilitar un\u00a0<strong>cambio de paradigma<\/strong> en la <strong>gesti\u00f3n de las personas.\u00a0<\/strong><\/p>\n<p>Conceptualmente, estos son los tres pilares en los que nos apoyamos para el citado despliegue:<\/p>\n<ol>\n<li>La <strong>gesti\u00f3n por competencias<\/strong> y la <strong>matriz competencial<\/strong><\/li>\n<li>La <strong>evaluaci\u00f3n del desempe\u00f1o<\/strong><\/li>\n<li>La <strong>matriz de talento<\/strong> de la organizaci\u00f3n<\/li>\n<\/ol>\n<p>Una vez implementado el <strong>sistema de gesti\u00f3n de personas<\/strong>, estos tres pilares se retroalimentan entre ellos constituyendo un <strong>c\u00edrculo virtuoso<\/strong> que aporta\u00a0<strong>valor<\/strong> y mejora el rendimiento de cada una de las personas de la organizaci\u00f3n.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice de contenidos <\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #3acdef;color:#3acdef\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #3acdef;color:#3acdef\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/#la-gestion-por-competencias\" >La gesti\u00f3n por competencias<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/#la-evaluacion-del-desempeno\" >La evaluaci\u00f3n del desempe\u00f1o<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/#la-matriz-del-talento\" >La matriz del talento<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"la-gestion-por-competencias\"><\/span>La gesti\u00f3n por competencias<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La base y el punto de partida est\u00e1n en la definici\u00f3n de los <strong>puestos de trabajo por competencias<\/strong> y en el an\u00e1lisis de la <strong>adecuaci\u00f3n persona-puesto<\/strong>. Una buena definici\u00f3n de puestos y una bien trabajada y sistematizada evaluaci\u00f3n de las personas por competencias nos permitir\u00e1n una <strong>gesti\u00f3n integral<\/strong> en el departamento: selecci\u00f3n de personal, planes de formaci\u00f3n, planes de sucesi\u00f3n o de carrera, planes de polivalencia, pol\u00edticas retributivas, etc. Ambos procesos son decisivos\u00a0para la implantaci\u00f3n con \u00e9xito de un <strong>modelo de desarrollo de las personas de la organizaci\u00f3n.<\/strong><\/p>\n<figure id=\"attachment_2086\" aria-describedby=\"caption-attachment-2086\" style=\"width: 350px\" class=\"wp-caption alignright\"><a class=\"lightbox\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/talento-a-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2086 size-full\" title=\"Matriz competencial\" src=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/talento-a-1.jpg\" alt=\"talento-a\" width=\"350\" height=\"336\" \/><\/a><figcaption id=\"caption-attachment-2086\" class=\"wp-caption-text\">Matriz competencial<\/figcaption><\/figure>\n<p>Respecto al an\u00e1lisis por competencias existen muchos sistemas descritos, si bien podr\u00edamos destacar los que se asientan sobre <strong>modelos de comportamiento;\u00a0<\/strong>en segundo lugar, aunque<strong>\u00a0<\/strong>usados\u00a0en menor medida en el entorno empresarial, los que se enfocan en <strong>modelos funcionales<\/strong>; y por \u00faltimo,<strong> modelos mixtos<\/strong> que incorporan aspectos de ambos.<\/p>\n<p>En las pr\u00f3ximas semanas dedicaremos un art\u00edculo a comentar las <strong>fortalezas<\/strong> y <strong>debilidades<\/strong> que la pr\u00e1ctica est\u00e1 revelando para cada uno de los citados modelos.<\/p>\n<p>El an\u00e1lisis de la adecuaci\u00f3n <strong>persona-puesto<\/strong> nos da una primera y r\u00e1pida visi\u00f3n de los <em>gaps<\/em>, divergencias o saltos competenciales de cada persona, as\u00ed como de los espacios de mejora y posibilidades para el desarrollo profesional y personal.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"la-evaluacion-del-desempeno\"><\/span>La evaluaci\u00f3n del desempe\u00f1o<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>El desarrollo perseguido por los <strong>modelos<\/strong> m\u00e1s <strong>humanistas<\/strong> se ha centrado principalmente en la <strong>reducci\u00f3n de los <em>gaps<\/em> competenciales<\/strong>, en contra de\u00a0lo que planteaban los <strong>modelos<\/strong>\u00a0<strong>economicistas,<\/strong>\u00a0que apostaban por una evaluaci\u00f3n del desempe\u00f1o determinada casi exclusivamente por la consecuci\u00f3n de unos <strong>objetivos cuantitativos<\/strong>.<\/p>\n<p>En los modelos basados en el <strong>nuevo paradigma<\/strong>, los dos factores anteriores (qu\u00e9 objetivos perseguimos y c\u00f3mo actuamos para conseguirlos) aparecen como <strong>aportadores de informaci\u00f3n<\/strong> que se complementan en el <strong>cuadro de mando<\/strong> del desempe\u00f1o de cada persona.<\/p>\n<p>Por supuesto, este <strong>cuadro de mando del desempe\u00f1o<\/strong> debe ser negociado con la persona. Para lograr el sentimiento de pertenencia y el compromiso no hay subterfugios: la persona debe tener voz y voto en su propio desarrollo y sentirse <strong>part\u00edcipe<\/strong> e involucrada en la consecuci\u00f3n de los objetivos marcados, recogiendo sus expectativas de <strong>crecimiento personal y profesional.<\/strong><\/p>\n<figure id=\"attachment_2104\" aria-describedby=\"caption-attachment-2104\" style=\"width: 450px\" class=\"wp-caption aligncenter\"><a class=\"lightbox\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/talento-b-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2104\" src=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/talento-b-2.jpg\" alt=\"Cuadro de evaluaci\u00f3n del desempe\u00f1o\" width=\"450\" height=\"334\" \/><\/a><figcaption id=\"caption-attachment-2104\" class=\"wp-caption-text\">Cuadro de evaluaci\u00f3n del desempe\u00f1o<\/figcaption><\/figure>\n<p>Como hemos visto, este cuadro de desempe\u00f1o contemplar\u00e1 <strong>dos tipos de objetivos<\/strong>:<\/p>\n<ol>\n<li><strong>Cualitativos<\/strong>: la <strong>mejora<\/strong> de algunas de las <strong>competencias<\/strong>, normalmente de las denominadas \u201cblandas\u201d o \u201cestar\u201d, con mayor <em>gap<\/em> para su desempe\u00f1o profesional actual o futuro (planes de carrera o sucesi\u00f3n).<\/li>\n<li><strong>Cuantitativos<\/strong>: <strong>metas concretas<\/strong> a alcanzar en el per\u00edodo de evaluaci\u00f3n (n\u00famero de nuevos clientes, de mejoras introducidas, incremento de la satisfacci\u00f3n, etc.).Conviene recordar tambi\u00e9n que\u00a0incluir <strong>planes de acci\u00f3n<\/strong>\u00a0y <strong>actividades concretas<\/strong> que se deben completar con \u00e9xito (objetivos cuantitativos) facilitar\u00e1 el seguimiento y la consecuci\u00f3n de los <strong>objetivos cualitativos<\/strong>. Por lo que finalmente ambos tipos de objetivos se necesitan y complementan entre s\u00ed.<\/li>\n<\/ol>\n<p>Por tanto, y tal como refleja el <em>cuadro de evaluaci\u00f3n del desempe\u00f1o<\/em> m\u00e1s arriba, la evaluaci\u00f3n del desempe\u00f1o debe permitir un seguimiento continuo, sencillo y eficaz tanto de los objetivos y el desarrollo de competencias, como del cumplimiento de metas y de los planes de acci\u00f3n desplegados para su consecuci\u00f3n.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"la-matriz-del-talento\"><\/span>La matriz del talento<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Tras la evaluaci\u00f3n del desempe\u00f1o, la <strong>matriz del talento,<\/strong> nos permite visualizar de una forma sencilla el <strong>posicionamiento relativo<\/strong> del talento de la organizaci\u00f3n y tomar decisiones consensuadas con los afectados para retroalimentar toda la gesti\u00f3n de las personas: analizar qu\u00e9 competencias deben ser trabajadas en mayor medida, plantear planes de acci\u00f3n y modificar o crear nuevos objetivos de desempe\u00f1o con cada una de las personas.<br \/>\nLa matriz del talento nos posiciona a las personas en \u201cnueve cajas\u201d seg\u00fan el cumplimiento actual de su <strong>desempe\u00f1o<\/strong> (eje X) y su <strong>nivel competencial<\/strong> (eje Y).<\/p>\n<figure id=\"attachment_2094\" aria-describedby=\"caption-attachment-2094\" style=\"width: 500px\" class=\"wp-caption aligncenter\"><a class=\"lightbox\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/talento-c.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2094\" src=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/talento-c.jpg\" alt=\"Matriz del talento\" width=\"500\" height=\"379\" \/><\/a><figcaption id=\"caption-attachment-2094\" class=\"wp-caption-text\">Matriz del talento<\/figcaption><\/figure>\n<p>Por \u00faltimo, a nivel gerencial y departamental, la <strong>matriz competencial<\/strong> es una herramienta que facilita la toma de decisiones a direcci\u00f3n, de forma sencilla, para el despliegue de cualquier <strong>modelo subcompetencial<\/strong> que se considere estrat\u00e9gico en la organizaci\u00f3n.<br \/>\nPor ejemplo, si estamos inmersos en un proceso de gesti\u00f3n del cambio digital, realizar\u00edamos el seguimiento de las competencias deseadas para esa transformaci\u00f3n digital, pudiendo ver en la matriz los niveles deseados de cada una frente a los niveles reales, de forma tanto agrupada (organizacional o departamental) como individual.<\/p>\n<p>Otros ejemplos ser\u00edan el desarrollo de un <strong>modelo de liderazgo<\/strong>, monitorizando aquellas competencias que consideramos clave para nuestros directivos y\/o mandos, o para un modelo de innovaci\u00f3n, o incluso, en la gesti\u00f3n y desarrollo de las personas de los diferentes departamentos de la empresa, donde las competencias deseadas ser\u00edan las propias de cada departamento: comercial, tecnolog\u00eda, administraci\u00f3n,\u2026<\/p>\n<p>A trav\u00e9s de estas matrices, soluciones inform\u00e1ticas que integran estas herramientas, gerencia con sus directivos y mandos, y cada responsable intermedio con su equipo, ya se puede comenzar, de una forma pr\u00e1ctica y sencilla, el <strong>cambio de paradigma<\/strong> en la gesti\u00f3n de las personas de una organizaci\u00f3n.<\/p>\n<p>Aunque no debemos olvidar que, en este nuevo enfoque, los <strong>directivos<\/strong> y <strong>mandos<\/strong> adquieren un papel protagonista en el seguimiento y el\u00a0<strong>desarrollo de sus equipos<\/strong> y que por tanto debemos, desde el desarrollo de las personas, facilitarles las competencias para que ejerzan esta nueva labor de forma eficaz.<\/p>\n<p>Si quer\u00e9is ampliar m\u00e1s informaci\u00f3n, pod\u00e9is descargaros la grabaci\u00f3n del <strong><a href=\"http:\/\/www.proquo.pro\/mas\/eventos\/conoce-la-solucion-para-gestionar-los-recursos-humanos-y-el-talento-de-tu-organizacion\" target=\"_blank\" rel=\"noopener\">Webinar Conoce la soluci\u00f3n para gestionar los Recursos Humanos y el talento de tu organizaci\u00f3n.<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En este segundo art\u00edculo, os presentamos una propuesta de c\u00f3mo, desde las organizaciones, podemos desplegar y facilitar un\u00a0cambio de paradigma en la gesti\u00f3n de las personas.\u00a0 Conceptualmente, estos son los tres pilares en los que nos apoyamos para el citado despliegue: La gesti\u00f3n por competencias y la matriz competencial La evaluaci\u00f3n del desempe\u00f1o La matriz [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":8812,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[84],"tags":[211],"class_list":["post-2072","post","type-post","status-publish","format-standard","has-post-thumbnail","category-gestion-del-talento","tag-rrhh","entry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Os presentamos una propuesta de c\u00f3mo, desde las organizaciones, podemos desplegar y facilitar un cambio de paradigma en la gesti\u00f3n de las personas.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Boris Giambanco\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"La Innovaci\u00f3n Necesaria | Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Nueva gesti\u00f3n del talento | La Innovaci\u00f3n Necesaria\" \/>\n\t\t<meta property=\"og:description\" content=\"Os presentamos una propuesta de c\u00f3mo, desde las organizaciones, podemos desplegar y facilitar un cambio de paradigma en la gesti\u00f3n de las personas.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-12-20T14:26:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-12-26T16:38:14+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Nueva gesti\u00f3n del talento | La Innovaci\u00f3n Necesaria\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Os presentamos una propuesta de c\u00f3mo, desde las organizaciones, podemos desplegar y facilitar un cambio de paradigma en la gesti\u00f3n de las personas.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\\\/#article\",\"name\":\"Nueva gesti\\u00f3n del talento | La Innovaci\\u00f3n Necesaria\",\"headline\":\"Las personas, centro de la estrategia de las organizaciones (Parte II)\",\"author\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/boris_efor\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/slider-personas-2.jpg\",\"width\":1349,\"height\":250},\"datePublished\":\"2016-12-20T15:26:10+01:00\",\"dateModified\":\"2023-12-26T17:38:14+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\\\/#webpage\"},\"articleSection\":\"Talento y RRHH, rrhh\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/categorias\\\/gestion-del-talento\\\/#listItem\",\"name\":\"Talento y RRHH\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/categorias\\\/gestion-del-talento\\\/#listItem\",\"position\":2,\"name\":\"Talento y RRHH\",\"item\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/categorias\\\/gestion-del-talento\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\\\/#listItem\",\"name\":\"Las personas, centro de la estrategia de las organizaciones (Parte II)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\\\/#listItem\",\"position\":3,\"name\":\"Las personas, centro de la estrategia de las organizaciones (Parte II)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/categorias\\\/gestion-del-talento\\\/#listItem\",\"name\":\"Talento y RRHH\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#organization\",\"name\":\"La Innovaci\\u00f3n Necesaria\",\"description\":\"Blog sobre tecnolog\\u00eda, business intelligence, marketing digital, cloud y seguridad.\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-integra-blanco.svg\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\\\/#organizationLogo\",\"width\":165,\"height\":38},\"image\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/boris_efor\\\/#author\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/boris_efor\\\/\",\"name\":\"Boris Giambanco\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\\\/#authorImage\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/boris.png\",\"width\":96,\"height\":96,\"caption\":\"Boris Giambanco\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\\\/#webpage\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\\\/\",\"name\":\"Nueva gesti\\u00f3n del talento | La Innovaci\\u00f3n Necesaria\",\"description\":\"Os presentamos una propuesta de c\\u00f3mo, desde las organizaciones, podemos desplegar y facilitar un cambio de paradigma en la gesti\\u00f3n de las personas.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/boris_efor\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/boris_efor\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/slider-personas-2.jpg\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\\\/#mainImage\",\"width\":1349,\"height\":250},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\\\/#mainImage\"},\"datePublished\":\"2016-12-20T15:26:10+01:00\",\"dateModified\":\"2023-12-26T17:38:14+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#website\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/\",\"name\":\"La Innovaci\\u00f3n Necesaria\",\"description\":\"Blog sobre tecnolog\\u00eda, business intelligence, marketing digital, cloud y seguridad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Nueva gesti\u00f3n del talento | La Innovaci\u00f3n Necesaria","description":"Os presentamos una propuesta de c\u00f3mo, desde las organizaciones, podemos desplegar y facilitar un cambio de paradigma en la gesti\u00f3n de las personas.","canonical_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/#article","name":"Nueva gesti\u00f3n del talento | La Innovaci\u00f3n Necesaria","headline":"Las personas, centro de la estrategia de las organizaciones (Parte II)","author":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/boris_efor\/#author"},"publisher":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/slider-personas-2.jpg","width":1349,"height":250},"datePublished":"2016-12-20T15:26:10+01:00","dateModified":"2023-12-26T17:38:14+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/#webpage"},"isPartOf":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/#webpage"},"articleSection":"Talento y RRHH, rrhh"},{"@type":"BreadcrumbList","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria#listItem","position":1,"name":"Inicio","item":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria","nextItem":{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/gestion-del-talento\/#listItem","name":"Talento y RRHH"}},{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/gestion-del-talento\/#listItem","position":2,"name":"Talento y RRHH","item":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/gestion-del-talento\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/#listItem","name":"Las personas, centro de la estrategia de las organizaciones (Parte II)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/#listItem","position":3,"name":"Las personas, centro de la estrategia de las organizaciones (Parte II)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/gestion-del-talento\/#listItem","name":"Talento y RRHH"}}]},{"@type":"Organization","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#organization","name":"La Innovaci\u00f3n Necesaria","description":"Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/","logo":{"@type":"ImageObject","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/#organizationLogo","width":165,"height":38},"image":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/boris_efor\/#author","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/boris_efor\/","name":"Boris Giambanco","image":{"@type":"ImageObject","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/#authorImage","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/08\/boris.png","width":96,"height":96,"caption":"Boris Giambanco"}},{"@type":"WebPage","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/#webpage","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/","name":"Nueva gesti\u00f3n del talento | La Innovaci\u00f3n Necesaria","description":"Os presentamos una propuesta de c\u00f3mo, desde las organizaciones, podemos desplegar y facilitar un cambio de paradigma en la gesti\u00f3n de las personas.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#website"},"breadcrumb":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/#breadcrumblist"},"author":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/boris_efor\/#author"},"creator":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/boris_efor\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/slider-personas-2.jpg","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/#mainImage","width":1349,"height":250},"primaryImageOfPage":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/#mainImage"},"datePublished":"2016-12-20T15:26:10+01:00","dateModified":"2023-12-26T17:38:14+01:00"},{"@type":"WebSite","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#website","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/","name":"La Innovaci\u00f3n Necesaria","description":"Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#organization"}}]},"og:locale":"es_ES","og:site_name":"La Innovaci\u00f3n Necesaria | Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.","og:type":"article","og:title":"Nueva gesti\u00f3n del talento | La Innovaci\u00f3n Necesaria","og:description":"Os presentamos una propuesta de c\u00f3mo, desde las organizaciones, podemos desplegar y facilitar un cambio de paradigma en la gesti\u00f3n de las personas.","og:url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/","og:image":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg","og:image:secure_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg","article:published_time":"2016-12-20T14:26:10+00:00","article:modified_time":"2023-12-26T16:38:14+00:00","twitter:card":"summary","twitter:title":"Nueva gesti\u00f3n del talento | La Innovaci\u00f3n Necesaria","twitter:description":"Os presentamos una propuesta de c\u00f3mo, desde las organizaciones, podemos desplegar y facilitar un cambio de paradigma en la gesti\u00f3n de las personas.","twitter:image":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg"},"aioseo_meta_data":{"post_id":"2072","title":"Nueva gesti\u00f3n del talento  | #site_title","description":"Os presentamos una propuesta de c\u00f3mo, desde las organizaciones, podemos desplegar y facilitar un cambio de paradigma en la gesti\u00f3n de las personas.","keywords":[{"label":"talento","value":"talento"},{"label":"recursos humanos","value":"recursos humanos"},{"label":"estrategia","value":"estrategia"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-09-28 14:45:52","updated":"2022-09-16 09:20:49","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/gestion-del-talento\/\" title=\"Talento y RRHH\">Talento y RRHH<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLas personas, centro de la estrategia de las organizaciones (Parte II)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria"},{"label":"Talento y RRHH","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/gestion-del-talento\/"},{"label":"Las personas, centro de la estrategia de las organizaciones (Parte II)","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-ii\/"}],"_links":{"self":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/2072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/comments?post=2072"}],"version-history":[{"count":0,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/2072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media\/8812"}],"wp:attachment":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media?parent=2072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/categories?post=2072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/tags?post=2072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}