
  
{"id":2749,"date":"2017-07-25T09:02:40","date_gmt":"2017-07-25T07:02:40","guid":{"rendered":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/?p=2749"},"modified":"2023-12-26T17:41:29","modified_gmt":"2023-12-26T16:41:29","slug":"millennials-los-lideres-de-la-cuarta-revolucion-industrial","status":"publish","type":"post","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/millennials-los-lideres-de-la-cuarta-revolucion-industrial\/","title":{"rendered":"Millennials, los l\u00edderes de la cuarta Revoluci\u00f3n Industrial"},"content":{"rendered":"<p>Hace unas semanas\u00a0asist\u00ed a una charla en el Patio de la Infanta de Ibercaja en Zaragoza que, si bien no me resultaba de inter\u00e9s <em>a priori<\/em>, debo reconocer que me ha llevado a reflexionar profundamente sobre la captaci\u00f3n de talento en la \u201carchiconocida\u201d generaci\u00f3n millennial&#8230;\u00bfo no tan conocida?<\/p>\n<p>Tras leer detenidamente el libro que en tal evento nos presentaba uno de sus coordinadores, Jos\u00e9 Mar\u00eda \u00c1lvarez Monzoncillo, Catedr\u00e1tico de Comunicaci\u00f3n Audiovisual de la Universidad Rey Juan Carlos de Madrid, titulado \u201c<strong><em>Millennials,<\/em> la generaci\u00f3n emprendedora<\/strong>\u201d he podido conocer y documentarme sobre dicha generaci\u00f3n, que en pocos a\u00f1os supondr\u00e1 m\u00e1s del 50% del mercado laboral, por lo que comparto a continuaci\u00f3n mis reflexiones.<\/p>\n<p>Hace unos meses, en este mismo blog pod\u00edamos leer un art\u00edculo titulado <a href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/las-personas-centro-de-la-estrategia-de-las-organizaciones-parte-i\/\" target=\"_blank\" rel=\"noopener\">Las personas, centro de la estrategia de las organizaciones<\/a>, donde mi compa\u00f1ero Boris Giambanco hablaba sobre el <strong>cambio de paradigma<\/strong> a la hora de captar y retener a esta generaci\u00f3n que empieza a crecer en presencia en el mundo de la empresa.<\/p>\n<p>Si bien la generaci\u00f3n anterior, conocida como <strong>Generaci\u00f3n X<\/strong> (actualmente entre 37-51 a\u00f1os) sigue siendo mayoritaria en cuanto a tasa de empleados en el mundo empresarial, no es menos cierto que la <strong>Generaci\u00f3n Y<\/strong>\u00a0(que cuenta ahora entre 22-36 a\u00f1os), los <em><strong>Millennials<\/strong><\/em>, van ascendiendo a puestos de responsabilidad.<\/p>\n<p>Uno de los desaf\u00edos m\u00e1s grandes al que nos enfrentamos en el mundo de la empresa es entender los deseos y aspiraciones de esta generaci\u00f3n, as\u00ed como sus h\u00e1bitos de consumo, su nivel de formaci\u00f3n, su actitud ante el desempleo y su nueva formar de trabajar.<\/p>\n<p>Seg\u00fan <strong>Harvard Business Review<\/strong> en su estudio <a href=\"https:\/\/hbr.org\/2016\/11\/the-best-performing-ceos-in-the-world#roundtable\" target=\"_blank\" rel=\"noopener\">Qu\u00e9 temen los nuevos CEO<\/a>, no existen conocimientos adecuados que puedan impartirse a <em>managers<\/em> en lo que a la gesti\u00f3n de esta generaci\u00f3n y sus caracter\u00edsticas diferenciadoras se refiere, por lo que se hace necesario adecuarse a la realidad del momento y estudiar sus peculiaridades.<\/p>\n<p>Personalmente, encuentro muchas dificultades a la hora de homogeneizar los patrones de comportamiento de un colectivo, por el hecho de haber nacido en una d\u00e9cada coincidente, pero no es menos cierto, que disponemos de estad\u00edsticas suficientes como para arrojar algunas conclusiones, que resumo en tres a continuaci\u00f3n:<\/p>\n<ul>\n<li><strong><em>Millennials<\/em>, la generaci\u00f3n emprendedora<\/strong>: t\u00edtulo del libro que mentaba al comienzo y cuyos autores afirman se trata de un segmento con claro esp\u00edritu emprendedor e innovador. En realidad, el emprendimiento viene impulsado m\u00e1s bien como respuesta a una necesidad, no en vano en el contexto nacional nos enfrentamos a unas tasas muy elevadas de desempleo juvenil. Sin embargo, entendiendo el emprendimiento e innovaci\u00f3n como el acto de acometer un negocio (definici\u00f3n de la RAE), debemos destacar que, dentro de las cincuenta <em>start-ups<\/em> con mayor futuro, en, al menos, la mitad de ellas participa como socio fundador alg\u00fan <em>millennial.<\/em><\/li>\n<li><strong>La tasa de movilidad de los <em>millennials<\/em> es muy alta<\/strong> y, seg\u00fan diversos estudios de empresas expertas en recursos humanos, la conclusi\u00f3n es la misma: la mayor\u00eda de j\u00f3venes aspira a cambiar de trabajo en un tiempo m\u00e1ximo de dos a cinco a\u00f1os. Por ello, debemos plantearnos hasta qu\u00e9 punto debemos trabajar en ese <em>engagement<\/em>, en ese sentimiento de permanencia, con este perfil de trabajadores que parecen tener clara su rotaci\u00f3n en el mercado laboral. Una encuesta realizada en 29 pa\u00edses a unas 7.700 personas (Deloitte, 2016) indica que dos de cada tres <em>millennials<\/em> piensan dejar su empleo en los dos pr\u00f3ximos a\u00f1os.<\/li>\n<li><strong>Cambio en los soportes de publicaci\u00f3n de ofertas laborales:<\/strong> nos enfrentamos al descenso en afluencia de algunos portales y consultor\u00edas de selecci\u00f3n en pro de <strong>redes sociales<\/strong>, y no s\u00f3lo las puramente profesionales, como LinkedIn, sino tambi\u00e9n Facebook y Twitter dejan de ser espacios de ocio para pasar a convertirse en fuentes de informaci\u00f3n social, profesional y laboral. Incluso algunas redes audiovisuales se estrenan en la oferta de empleos, como Snapchat. No en vano, los <em>millennials<\/em> van a poder utilizar su aplicaci\u00f3n preferida para solicitar un puesto de trabajo. Sirva como ejemplo McDonald\u00b4s, cadena que ha colaborado con esta aplicaci\u00f3n para que sirva como medio de consecuci\u00f3n de un empleo en alguno de sus restaurantes a partir de verano de 2017, ofreciendo un total de 250.000 puestos de trabajo.<\/li>\n<\/ul>\n<p>Adem\u00e1s de estas tres caracter\u00edsticas globales principales, me gustar\u00eda concluir destacando\u00a0algunos rasgos comunes que espero ayuden a los profesionales de las \u00e1reas de captaci\u00f3n y gesti\u00f3n de personas al conocimiento de esta generaci\u00f3n: <strong>tolerancia<\/strong> al cambio, apertura a <strong>nuevas experiencias<\/strong>, orientaci\u00f3n al <strong>trabajo colaborativo<\/strong>, transparencia, contextos organizativos m\u00e1s flexibles, equipos <strong>multidisciplinares<\/strong>, valoraci\u00f3n de objetivos a corto plazo, intensidad en la comunicaci\u00f3n, dominio de nuevas tecnolog\u00edas, h\u00edper conexi\u00f3n y amplitud en sus redes de contactos y <strong>empoderamiento digital.<\/strong><\/p>\n<p>Con todas sus caracter\u00edsticas, ser\u00e1n nuestros millennials los que liderar\u00e1n la <strong>Cuarta Revoluci\u00f3n Industrial<\/strong> que hace unos meses vislumbraban algunos, como Pilar L\u00f3pez, presidenta de Microsoft Ib\u00e9rica y en la que ya estamos sumergidos a gran escala y a toda velocidad. Un motivo m\u00e1s que suficiente para conocerlos adecuadamente, \u00bfno os parece?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace unas semanas\u00a0asist\u00ed a una charla en el Patio de la Infanta de Ibercaja en Zaragoza que, si bien no me resultaba de inter\u00e9s a priori, debo reconocer que me ha llevado a reflexionar profundamente sobre la captaci\u00f3n de talento en la \u201carchiconocida\u201d generaci\u00f3n millennial&#8230;\u00bfo no tan conocida? Tras leer detenidamente el libro que en [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":9099,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[84],"tags":[],"class_list":{"0":"post-2749","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-gestion-del-talento","8":"entry"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/2749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/comments?post=2749"}],"version-history":[{"count":0,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/2749\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media\/9099"}],"wp:attachment":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media?parent=2749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/categories?post=2749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/tags?post=2749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}