
  
{"id":314,"date":"2015-03-23T16:42:48","date_gmt":"2015-03-23T15:42:48","guid":{"rendered":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/?p=314"},"modified":"2023-12-26T17:32:08","modified_gmt":"2023-12-26T16:32:08","slug":"apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones","status":"publish","type":"post","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/","title":{"rendered":"APPs en movilidad: distintas tendencias en el desarrollo de aplicaciones"},"content":{"rendered":"<p>En estos \u00faltimos a\u00f1os, de una forma completamente exponencial, hemos visto como el uso de los tel\u00e9fonos m\u00f3viles inteligentes (s<em>martphones<\/em>) se ha convertido en una \u201c<em>commodity<\/em>\u201d para los usuarios.<\/p>\n<p>Cada vez los dispositivos son m\u00e1s potentes, las comunicaciones son mejores y existe un mayor n\u00famero de apps\u00a0de servicio a los usuarios (tanto en el \u00e1mbito personal como en el profesional).<\/p>\n<p>En este post, vamos a intentar mostrar de qu\u00e9 forma el uso de terminales m\u00f3viles (<em>smarphones<\/em> o <em>tablets<\/em>) puede incrementar la productividad empresarial y sobre todo, las tendencias tecnol\u00f3gicas actuales en el \u00e1mbito de las apps\u00a0(pros-contras, c\u00f3mo elegir una tecnolog\u00eda para desarrollar una aplicaci\u00f3n, etc.).<\/p>\n<p><strong>Antes de nada, un poco de historia\u2026<\/strong><\/p>\n<p>Para situar en contexto la situaci\u00f3n actual, vamos a mostrar de forma r\u00e1pida la evoluci\u00f3n que ha existido en el mundo de la movilidad.<\/p>\n<p><a class=\"lightbox\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/moviles.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-317 alignleft\" src=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/moviles.jpg\" alt=\"Evolucion de dispositivos moviles\" width=\"359\" height=\"487\" \/><\/a><\/p>\n<p>Desde hace 15 a\u00f1os hasta la actualidad ha habido una gran y continua evoluci\u00f3n tecnol\u00f3gica de los dispositivos m\u00f3viles.<\/p>\n<p>En su momento su \u00fanico uso era la realizaci\u00f3n de llamadas, y sin embargo en la actualidad los <em>smartphones<\/em> o <em>tablets<\/em> sirven para cualquier funci\u00f3n (c\u00e1mara, reproductor de m\u00fasica, consola de videojuegos, GPS, <em>eBook<\/em>, ordenador port\u00e1til\u2026 e \u00a1incluso como tel\u00e9fono!).<\/p>\n<p>Tambi\u00e9n ha influido de una forma fundamental la continua mejora de las redes de comunicaciones, que nos permiten conectarnos y \u201cnavegar\u201d con una mayor rapidez y con un abaratamiento de costes.<\/p>\n<p>Hasta el a\u00f1o 2007, los tel\u00e9fonos catalogados como s<em>martphones<\/em> dispon\u00edan de aplicaciones ya preinstaladas (agenda, contactos, juegos, incluso el correo) y para su conexi\u00f3n a Internet exist\u00edan tecnolog\u00edas como EDGE (que permit\u00eda ampliar el n\u00famero de aplicaciones disponibles en los dispositivos). Se trabajaba en la b\u00fasqueda de protocolos abiertos como WAP, para el acceso a servicios de Internet desde un tel\u00e9fono m\u00f3vil.<\/p>\n<p>Pero el principal problema eran las restricciones debido a que cada fabricante dispon\u00eda de su propio sistema operativo para el desarrollo de funcionalidades.<\/p>\n<p>A partir del a\u00f1o 2007 hay un punto de inflexi\u00f3n en el mundo de la movilidad. Apple presenta su modelo iPhone, que supone un cambio de concepto: el dispositivo m\u00f3vil se plantea como una plataforma sobre la que se pueden desarrollar aplicaciones desarrolladas por terceros.<\/p>\n<p><a class=\"lightbox\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/apps.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-319\" src=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/apps.jpg\" alt=\"evoluci\u00f3n de apps\" width=\"381\" height=\"318\" \/><\/a><\/p>\n<p>Adem\u00e1s, nace Android, un sistema operativo <em>open-source<\/em>, lo que supone un aumento de n\u00famero de terminales, smartphones de bajo costo\u2026<\/p>\n<p>Como dato interesante destacar que a principios de 2008 <em>appStore<\/em> contaba con 500 aplicaciones, en la actualidad dispone de 1,2 millones de apps. Adem\u00e1s, en el 2014, <em>googlePlay<\/em> ha superado a <em>appStore<\/em> en cuanto a n\u00famero de aplicaciones disponibles.<\/p>\n<p><strong>Y la actualidad\u2026<\/strong><\/p>\n<p>Seg\u00fan las conclusiones del VI Estudio Anual de Mobile Marketing (Comisi\u00f3n de Mobile de Lab Spain) la situaci\u00f3n actual, y en concreto en Espa\u00f1a, es:<\/p>\n<p>\u2022 El aumento de usuarios propietarios de un smartphone sigue al alza, hasta tal punto que el nivel de penetraci\u00f3n en la poblaci\u00f3n espa\u00f1ola es del 87% de internautas, lo que significa el 56% de la poblaci\u00f3n en Espa\u00f1a.<br \/>\n\u2022 El tiempo de conexi\u00f3n de media a trav\u00e9s del m\u00f3vil (el 81% de los usuarios de Internet) es de 2 horas y 32 minutos diarios. A trav\u00e9s de Tablet: casi 2 horas.<br \/>\n\u2022 El Smartphone tiene cada vez m\u00e1s protagonismo en la decisi\u00f3n de compra:o El 90% utiliza el m\u00f3vil a la hora de decidirse.<\/p>\n<p>o El 80% lo utiliza para buscar informaci\u00f3n sobre las caracter\u00edsticas que se est\u00e1 comprando, precios, art\u00edculos \u00a0 \u00a0 similares, opiniones de otras personas, etc.<br \/>\no El 45% ha efectuado alguna compra a trav\u00e9s del dispositivo m\u00f3vil.<br \/>\no Los principales uso son: ocio, viajes e inform\u00e1tica.<br \/>\no Lo que motiv\u00f3 a la compra: La b\u00fasqueda (Search), los anuncios (display) y las Apps.<br \/>\no S\u00f3lo un 8% ha utilizado el m\u00f3vil como medio de pago, por lo que todav\u00eda tiene un enorme desarrollo<\/p>\n<p>Como conclusi\u00f3n podemos ver que actualmente existe un crecimiento exponencial del uso de los dispositivos y las aplicaciones m\u00f3viles motivado por:<\/p>\n<p>\u2022 N\u00famero de dispositivos m\u00f3viles.<br \/>\n\u2022 N\u00famero de APPs disponibles.<br \/>\n\u2022 Capacidad de los SmartPhones<\/p>\n<p><strong>Quiero hacer una APP, pero \u00bfc\u00f3mo?<\/strong><\/p>\n<p>Ahora bien, si una empresa quiere apostar y embarcarse en la movilidad como una herramienta para mejorar su productividad, lo primero de todo debe hacerse una serie de preguntas o reflexiones importantes:<\/p>\n<p>1. <strong>Coste que pueda asumir<\/strong>: aunque parezca una obviedad, el planteamiento econ\u00f3mico del proyecto permitir\u00e1 elegir la opci\u00f3n tecnol\u00f3gica sobre la que desarrollar su APP. Lo mejor es ser lo m\u00e1s realista posible en este punto y adaptarse a sus capacidades.<\/p>\n<p>2. <strong>Las caracter\u00edsticas y funcionalidades de su proyecto tecnol\u00f3gico<\/strong>: Valorar si quiere sacar rendimiento a los componentes del dispositivo como el GPS, la c\u00e1mara, etc\u2026 o si, por ejemplo, solo va a querer obtener datos de unas bases de datos de su empresa.<\/p>\n<p>3.<strong> Su modelo de negocio y el target al que se dirige<\/strong>: hay ciertos modelos de negocio donde los usuarios est\u00e1n acostumbrados a experiencias propias de una web app y otros a apps propiamente dichas. Puede ser interesante realizar un peque\u00f1o estudio de mercado para ayudarle a tomar la decisi\u00f3n.<\/p>\n<p>4. <strong>La complejidad del dise\u00f1o y la importancia que otorga a la experiencia de usuario<\/strong>: si es un perfeccionista, exige un dise\u00f1o totalmente personalizado, unos tiempos de respuesta espectaculares, quiere demostrar que sus proyectos son referencia de excelencia y su econom\u00eda lo permite, entonces la opci\u00f3n nativa es la mejor opci\u00f3n.<\/p>\n<p>5. <strong>La intenci\u00f3n de evolucionar su APP<\/strong>: obviamente no es lo mismo una app sencilla que pueda utilizar para acci\u00f3n concreta (calculadora, br\u00fajula, etc.) que otra que va a tener un sinf\u00edn de opciones y contenido y sobre la que pueda construir todo un modelo de negocio. A mayor complejidad, la decisi\u00f3n que tome de c\u00f3mo hacerlo puede suponer tu \u00e9xito o tu fracaso.<\/p>\n<p>6. <strong>La estructura de su empresa<\/strong>: para desarrollar tu proyecto puedes tener a desarrolladores en plantilla o a externalizar este proceso. Cuestiones como los derechos de autor sobre el c\u00f3digo fuente generado o el tipo de perfil tecnol\u00f3gico que puede contratar o subcontratar pueden ser fundamentales a la hora de tomar esta decisi\u00f3n de c\u00f3mo hacer la app.<\/p>\n<p><strong>Tendencias en el desarrollo de APPs<\/strong><\/p>\n<p>Una vez que hemos indicado una serie de preguntas o reflexiones importantes que una empresa debe hacerse antes de empezar a embarcarse en el mundo de la movilidad, voy a mostrar las distintas tendencias en la actualidad para el desarrollo de una APP. Las APPs se catalogan en tres grandes familias:<\/p>\n<p>\u2022 Aplicaciones nativas<br \/>\n\u2022 Aplicaciones h\u00edbridas<br \/>\n\u2022 Aplicaciones web<\/p>\n<p>Cada una de ellas tiene sus pros y contras y por tanto, es importante que una empresa sepa lo que quiere conseguir con su APP y en base a ello, elegir la forma de obtenerla.<br \/>\n<strong>Aplicaciones nativas<\/strong><br \/>\nUna APP nativa es una aplicaci\u00f3n que se desarrolla directamente en el lenguaje nativo de cada terminal:<br \/>\n\u2022 iOS: Objective C<br \/>\n\u2022 Android: Java<br \/>\n\u2022 Windows: C# y Visual Basic .NET.<br \/>\n\u2022 BlackBerry 10: C++<\/p>\n<p>Con una APP nativa, la experiencia de usuario es muy completa ya que su funcionamiento, rendimiento y respuesta es el m\u00e1s inmediato de todas las tecnolog\u00edas. Adem\u00e1s, brinda la posibilidad de disponer de dise\u00f1os gr\u00e1ficos m\u00e1s complejos y personalizados.<\/p>\n<p>Ventajas:<br \/>\n\u2022 Acceso a todo el hardware del m\u00f3vil como puede ser el GPS, la c\u00e1mara y dem\u00e1s accesorios.<br \/>\n\u2022 Acceso a todas las librer\u00edas gr\u00e1ficas del SO (botones, etc.).<br \/>\n\u2022 Env\u00edo de notificaciones push, una de las herramientas de comunicaci\u00f3n m\u00e1s potentes de las APPs.<br \/>\n\u2022 Aprovechar todas las ventajas que ofrece estar en las diferentes tiendas de aplicaciones (b\u00fasqueda de aplicaciones, aplicaciones gratuitas \u2013 aplicaciones de pago, modelos \u201cPremium\u201d, etc.).<br \/>\n\u2022 Sincronizar o cachear datos para poder trabajar sin conexi\u00f3n a internet.<\/p>\n<p>Inconvenientes:<br \/>\n\u2022 Principalmente, de tipo econ\u00f3mico. Al no ser compatibles los diferentes lenguajes de programaci\u00f3n y Sistemas Operativos de los SmartPhones, se deber\u00e1n programar tantas APPs como sistemas operativos (iOS, Android, Windows\u2026.).<br \/>\n\u2022 Todas las labores de mantenimiento, nuevas funcionalidades, etc., deber\u00e1n realizarse para cada plataforma (iOS, Android, Windows\u2026).<br \/>\n\u2022 Igualmente con cada nueva versi\u00f3n del sistema operativo correspondiente.<\/p>\n<p><strong>Aplicaciones h\u00edbridas<\/strong><br \/>\nUna app\u00a0h\u00edbrida se trata de una aplicaci\u00f3n que contiene en su interior el navegador web del dispositivo.<\/p>\n<p>Para su desarrollo se utilizan <em>frameworks<\/em> de desarrollo basados en lenguajes de programaci\u00f3n web (HTML, CSS y JS).<\/p>\n<p>Actualmente <strong>Phonegap<\/strong> es el m\u00e1s conocido (aunque no el \u00fanico) y el que concentra mayor n\u00famero de desarrolladores a su alrededor.<\/p>\n<p>En este tipo de apps el nivel de integraci\u00f3n con el sistema operativo del <em>SmartPhone<\/em> depender\u00e1 del <em>framework<\/em> de desarrollo utilizado y c\u00f3mo de abierto sea dicho sistema operativo.<br \/>\nVentajas:<br \/>\n\u2022 La principal ventaja es econ\u00f3mica: solo es necesario realizar un \u00fanico desarrollo, el cual es v\u00e1lido para cualquier plataforma m\u00f3vil.<br \/>\n\u2022 Su uso es una opci\u00f3n muy econ\u00f3mica y muy interesante para llegar al mayor n\u00famero de usuarios repartidos en las diferentes plataformas y dispositivos<br \/>\n\u2022 Asimismo, se tiene bastante acceso a distintos componentes del SmartPhone (c\u00e1mara, etc.).<br \/>\n\u2022 Los cambios de sistemas operativos o aumentos de funcionalidades de la aplicaci\u00f3n, no suponen un coste muy elevado.<\/p>\n<p>Inconvenientes:<\/p>\n<p>\u2022 El principal inconveniente es que, de momento, no se ha conseguido igualar la respuesta y la experiencia de usuario de una App nativa (aunque cada vez m\u00e1s, va camino de hacerlo).<\/p>\n<p><strong>Aplicaciones web<\/strong><\/p>\n<p>Una aplicaci\u00f3n web o web app es una web a la que se accede a trav\u00e9s de una URL en el navegador del dispositivo (Safari, Chrome o el que sea) y se adapta al formato de la pantalla para que tenga aspecto de navegaci\u00f3n App.<\/p>\n<p>Los navegadores de los m\u00f3viles permiten crear un acceso directo en el escritorio de esta web, as\u00ed que esa ser\u00e1 la manera de \u201cinstalarla\u201d (si se le puede llamar as\u00ed) en el dispositivo.<\/p>\n<p>En base al planteamiento econ\u00f3mico que se realice, si solo interesa adaptar la web a formato m\u00f3vil, en ese caso, realizar una web APP es la mejor soluci\u00f3n.<\/p>\n<p>Ventajas:<\/p>\n<p>\u2022 Reducci\u00f3n de coste de desarrollo, al poder realizarse de una misma vez la versi\u00f3n de una web \u201cest\u00e1ndar\u201d con la web adaptada o responsiva.<\/p>\n<p>Inconvenientes:<br \/>\n\u2022 Est\u00e1n altamente limitadas en el acceso al hardware del dispositivo.<br \/>\n\u2022 Tiempos de respuesta y experiencia de usuario propios de una navegaci\u00f3n web.<br \/>\n\u2022 No se encuentran en las Stores, siendo \u00e9ste el lugar donde la gente est\u00e1 acostumbrada a buscar apps.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En estos \u00faltimos a\u00f1os, de una forma completamente exponencial, hemos visto como el uso de los tel\u00e9fonos m\u00f3viles inteligentes (smartphones) se ha convertido en una \u201ccommodity\u201d para los usuarios. Cada vez los dispositivos son m\u00e1s potentes, las comunicaciones son mejores y existe un mayor n\u00famero de apps\u00a0de servicio a los usuarios (tanto en el \u00e1mbito [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":8423,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[365],"tags":[44,17],"class_list":["post-314","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tecnologia-para-la-empresa","tag-aplicaciones","tag-movilidad","entry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Las aplicaciones m\u00f3viles permiten incrementar la productividad empresarial, aqu\u00ed se muestran los beneficios, consejos y tipos de aplicaciones m\u00e1s \u00fatiles.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Iv\u00e1n Toda\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"La Innovaci\u00f3n Necesaria | Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Aplicaciones de movilidad para la empresa | La Innovaci\u00f3n Necesaria\" \/>\n\t\t<meta property=\"og:description\" content=\"Las aplicaciones m\u00f3viles permiten incrementar la productividad empresarial, aqu\u00ed se muestran los beneficios, consejos y tipos de aplicaciones m\u00e1s \u00fatiles.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-03-23T15:42:48+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-12-26T16:32:08+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Aplicaciones de movilidad para la empresa | La Innovaci\u00f3n Necesaria\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Las aplicaciones m\u00f3viles permiten incrementar la productividad empresarial, aqu\u00ed se muestran los beneficios, consejos y tipos de aplicaciones m\u00e1s \u00fatiles.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\\\/#article\",\"name\":\"Aplicaciones de movilidad para la empresa | La Innovaci\\u00f3n Necesaria\",\"headline\":\"APPs en movilidad: distintas tendencias en el desarrollo de aplicaciones\",\"author\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/itoda_efor\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/desarrollo-aplicaciones-moviles.jpg\",\"width\":1349,\"height\":220},\"datePublished\":\"2015-03-23T16:42:48+01:00\",\"dateModified\":\"2023-12-26T17:32:08+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\\\/#webpage\"},\"articleSection\":\"Tecnolog\\u00eda para la empresa, aplicaciones, Movilidad\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/categorias\\\/tecnologia-para-la-empresa\\\/#listItem\",\"name\":\"Tecnolog\\u00eda para la empresa\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/categorias\\\/tecnologia-para-la-empresa\\\/#listItem\",\"position\":2,\"name\":\"Tecnolog\\u00eda para la empresa\",\"item\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/categorias\\\/tecnologia-para-la-empresa\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\\\/#listItem\",\"name\":\"APPs en movilidad: distintas tendencias en el desarrollo de aplicaciones\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\\\/#listItem\",\"position\":3,\"name\":\"APPs en movilidad: distintas tendencias en el desarrollo de aplicaciones\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/categorias\\\/tecnologia-para-la-empresa\\\/#listItem\",\"name\":\"Tecnolog\\u00eda para la empresa\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#organization\",\"name\":\"La Innovaci\\u00f3n Necesaria\",\"description\":\"Blog sobre tecnolog\\u00eda, business intelligence, marketing digital, cloud y seguridad.\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-integra-blanco.svg\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\\\/#organizationLogo\",\"width\":165,\"height\":38},\"image\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/itoda_efor\\\/#author\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/itoda_efor\\\/\",\"name\":\"Iv\\u00e1n Toda\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\\\/#authorImage\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/wp-content\\\/uploads\\\/2015\\\/03\\\/ivan-150x150.jpg\",\"width\":96,\"height\":96,\"caption\":\"Iv\\u00e1n Toda\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\\\/#webpage\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\\\/\",\"name\":\"Aplicaciones de movilidad para la empresa | La Innovaci\\u00f3n Necesaria\",\"description\":\"Las aplicaciones m\\u00f3viles permiten incrementar la productividad empresarial, aqu\\u00ed se muestran los beneficios, consejos y tipos de aplicaciones m\\u00e1s \\u00fatiles.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/itoda_efor\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/itoda_efor\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/desarrollo-aplicaciones-moviles.jpg\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\\\/#mainImage\",\"width\":1349,\"height\":220},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\\\/#mainImage\"},\"datePublished\":\"2015-03-23T16:42:48+01:00\",\"dateModified\":\"2023-12-26T17:32:08+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#website\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/\",\"name\":\"La Innovaci\\u00f3n Necesaria\",\"description\":\"Blog sobre tecnolog\\u00eda, business intelligence, marketing digital, cloud y seguridad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Aplicaciones de movilidad para la empresa | La Innovaci\u00f3n Necesaria","description":"Las aplicaciones m\u00f3viles permiten incrementar la productividad empresarial, aqu\u00ed se muestran los beneficios, consejos y tipos de aplicaciones m\u00e1s \u00fatiles.","canonical_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/#article","name":"Aplicaciones de movilidad para la empresa | La Innovaci\u00f3n Necesaria","headline":"APPs en movilidad: distintas tendencias en el desarrollo de aplicaciones","author":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/itoda_efor\/#author"},"publisher":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/desarrollo-aplicaciones-moviles.jpg","width":1349,"height":220},"datePublished":"2015-03-23T16:42:48+01:00","dateModified":"2023-12-26T17:32:08+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/#webpage"},"isPartOf":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/#webpage"},"articleSection":"Tecnolog\u00eda para la empresa, aplicaciones, Movilidad"},{"@type":"BreadcrumbList","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria#listItem","position":1,"name":"Inicio","item":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria","nextItem":{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/tecnologia-para-la-empresa\/#listItem","name":"Tecnolog\u00eda para la empresa"}},{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/tecnologia-para-la-empresa\/#listItem","position":2,"name":"Tecnolog\u00eda para la empresa","item":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/tecnologia-para-la-empresa\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/#listItem","name":"APPs en movilidad: distintas tendencias en el desarrollo de aplicaciones"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/#listItem","position":3,"name":"APPs en movilidad: distintas tendencias en el desarrollo de aplicaciones","previousItem":{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/tecnologia-para-la-empresa\/#listItem","name":"Tecnolog\u00eda para la empresa"}}]},{"@type":"Organization","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#organization","name":"La Innovaci\u00f3n Necesaria","description":"Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/","logo":{"@type":"ImageObject","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/#organizationLogo","width":165,"height":38},"image":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/itoda_efor\/#author","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/itoda_efor\/","name":"Iv\u00e1n Toda","image":{"@type":"ImageObject","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/#authorImage","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2015\/03\/ivan-150x150.jpg","width":96,"height":96,"caption":"Iv\u00e1n Toda"}},{"@type":"WebPage","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/#webpage","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/","name":"Aplicaciones de movilidad para la empresa | La Innovaci\u00f3n Necesaria","description":"Las aplicaciones m\u00f3viles permiten incrementar la productividad empresarial, aqu\u00ed se muestran los beneficios, consejos y tipos de aplicaciones m\u00e1s \u00fatiles.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#website"},"breadcrumb":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/#breadcrumblist"},"author":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/itoda_efor\/#author"},"creator":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/itoda_efor\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/desarrollo-aplicaciones-moviles.jpg","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/#mainImage","width":1349,"height":220},"primaryImageOfPage":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/#mainImage"},"datePublished":"2015-03-23T16:42:48+01:00","dateModified":"2023-12-26T17:32:08+01:00"},{"@type":"WebSite","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#website","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/","name":"La Innovaci\u00f3n Necesaria","description":"Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#organization"}}]},"og:locale":"es_ES","og:site_name":"La Innovaci\u00f3n Necesaria | Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.","og:type":"article","og:title":"Aplicaciones de movilidad para la empresa | La Innovaci\u00f3n Necesaria","og:description":"Las aplicaciones m\u00f3viles permiten incrementar la productividad empresarial, aqu\u00ed se muestran los beneficios, consejos y tipos de aplicaciones m\u00e1s \u00fatiles.","og:url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/","og:image":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg","og:image:secure_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg","article:published_time":"2015-03-23T15:42:48+00:00","article:modified_time":"2023-12-26T16:32:08+00:00","twitter:card":"summary","twitter:title":"Aplicaciones de movilidad para la empresa | La Innovaci\u00f3n Necesaria","twitter:description":"Las aplicaciones m\u00f3viles permiten incrementar la productividad empresarial, aqu\u00ed se muestran los beneficios, consejos y tipos de aplicaciones m\u00e1s \u00fatiles.","twitter:image":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg"},"aioseo_meta_data":{"post_id":"314","title":"Aplicaciones de movilidad para la empresa | #site_title","description":"Las aplicaciones m\u00f3viles permiten incrementar la productividad empresarial, aqu\u00ed se muestran los beneficios, consejos y tipos de aplicaciones m\u00e1s \u00fatiles.","keywords":[{"label":"aplicaciones","value":"aplicaciones"},{"label":"app","value":"app"},{"label":"movilidad","value":"movilidad"},{"label":"phonegap","value":"phonegap"}],"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-09-28 14:33:40","updated":"2022-09-16 07:51:02","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/tecnologia-para-la-empresa\/\" title=\"Tecnolog\u00eda para la empresa\">Tecnolog\u00eda para la empresa<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAPPs en movilidad: distintas tendencias en el desarrollo de aplicaciones\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria"},{"label":"Tecnolog\u00eda para la empresa","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/tecnologia-para-la-empresa\/"},{"label":"APPs en movilidad: distintas tendencias en el desarrollo de aplicaciones","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/apps-en-movilidad-distintas-tendencias-en-el-desarrollo-de-aplicaciones\/"}],"_links":{"self":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/comments?post=314"}],"version-history":[{"count":0,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/314\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media\/8423"}],"wp:attachment":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media?parent=314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/categories?post=314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/tags?post=314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}