
  
{"id":3282,"date":"2018-01-17T17:04:28","date_gmt":"2018-01-17T16:04:28","guid":{"rendered":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/?p=3282"},"modified":"2023-12-26T17:44:44","modified_gmt":"2023-12-26T16:44:44","slug":"tendencias-seo-en-2018","status":"publish","type":"post","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/tendencias-seo-en-2018\/","title":{"rendered":"Cinco tendencias clave para SEO en 2018"},"content":{"rendered":"<p>As\u00ed como en otras \u00e1reas del marketing digital como redes sociales, email marketing o SEM, los cambios y las novedades de este a\u00f1o se pueden detectar con facilidad y est\u00e1n bien definidos, el campo del <strong>SEO<\/strong> siempre se ha caracterizado por su <strong>\u00abpoca transparencia\u00bb.<\/strong><\/p>\n<p>Los grandes buscadores marcan sus propias reglas c\u00f3mo y cuando quieren y, en muchos casos, es dif\u00edcil adivinarlas para los profesionales de esta \u00e1rea.<\/p>\n<p>Pese a las inc\u00f3gnitas, hemos seleccionado 5 principales tendencias que no debes olvidar si quieres que tu sitio web <strong>tenga visibilidad en las b\u00fasquedas org\u00e1nicas<\/strong>:<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice de contenidos <\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #3acdef;color:#3acdef\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #3acdef;color:#3acdef\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/tendencias-seo-en-2018\/#crawl-budget\" >Crawl Budget<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/tendencias-seo-en-2018\/#el-proyecto-amp-accelerated-mobile-pages-de-google\" >El proyecto AMP (Accelerated Mobile Pages)&nbsp;de Google<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/tendencias-seo-en-2018\/#busqueda-por-voz\" >B\u00fasqueda por voz<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/tendencias-seo-en-2018\/#youtube\" >YouTube<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/tendencias-seo-en-2018\/#google-rich-answers\" >Google Rich Answers<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"crawl-budget\"><\/span>Crawl Budget<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Este concepto hace referencia al <strong>\u00abpresupuesto de rastreo\u00bb<\/strong>, es decir, la <strong>cantidad de recursos <\/strong>que Google destina a toda nuestra web para rastrearla.<\/p>\n<p>En 2018&nbsp;Crawl Budget y SEO ir\u00e1n de la mano y ser\u00e1n elementos diferenciadores&nbsp;de una p\u00e1gina web&nbsp;con respecto a su competencia. Los webmasters son bien conocedores de esto ya que ser\u00e1 uno de los puntos clave en el SEO de este a\u00f1o 2018 y en el que van a tener que trabajar mucho.<\/p>\n<p>Google tiene un presupuesto de rastreo estipulado para cada web. Por tanto, cuanto m\u00e1s trabajemos la <strong>optimizaci\u00f3n<\/strong> de nuestra web, <strong>m\u00e1s p\u00e1ginas<\/strong> de nuestro sitio podr\u00e1 rastrear Google, con&nbsp;<strong>mayor frecuencia <\/strong>y, por tanto, m\u00e1s p\u00e1ginas<strong>&nbsp;<\/strong>de nuestro sitio&nbsp;se podr\u00e1n posicionar arriba.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"el-proyecto-amp-accelerated-mobile-pages-de-google\"><\/span>El proyecto AMP <em>(Accelerated Mobile Pages)<\/em>&nbsp;de Google<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><a href=\"https:\/\/www.ampproject.org\/es\/\" target=\"_blank\" rel=\"noopener noreferrer\">AMP<\/a>&nbsp;se convirti\u00f3 en el \u00abgran conocido\u00bb de los t\u00e9cnicos SEO hace unos 2 a\u00f1os y,&nbsp;hoy en d\u00eda, contin\u00faa siendo un aspecto b\u00e1sico a tener en cuenta.<\/p>\n<p><a class=\"lightbox\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/seo-movil.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-3299\" src=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/seo-movil.jpg\" alt=\"proyecto amp\" width=\"230\" height=\"230\"><\/a><\/p>\n<p>El proyecto AMP es una iniciativa de c\u00f3digo abierto que busca, en l\u00edneas generales, mejorar una web y, en concreto, optimizarla&nbsp;para dispositivos m\u00f3viles. Es una tecnolog\u00eda que ha sido desarrollada para facilitar la <strong>carga de la p\u00e1gina web en el menor tiempo posible en los dispositivos m\u00f3viles.<\/strong><\/p>\n<p>AMP es considerado como un <strong>factor de clasificaci\u00f3n<\/strong>. Con el continuo y creciente uso de los dispositivos m\u00f3viles, esta tecnolog\u00eda proporciona a nuestra web la posibilidad de una carga casi instant\u00e1nea y aumenta la visibilidad org\u00e1nica de nuestra web en los mismos. Por esta raz\u00f3n, las empresas&nbsp;no paran de adoptar&nbsp;esta tecnolog\u00eda con la intenci\u00f3n de aumentar la tasa de retenci\u00f3n de usuarios.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"busqueda-por-voz\"><\/span>B\u00fasqueda por voz<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Es la evoluci\u00f3n natural en las b\u00fasquedas a trav\u00e9s de todas las plataformas que est\u00e1n a nuestro alcance: Siri, Google Now, Cortana o las que se desarrollen en un futuro.<\/p>\n<p>Desde que llegaron a nuestras manos nuestros inseparables smartphones, las <strong>b\u00fasquedas por voz<\/strong> comenzaron a decaer en pro de las b\u00fasquedas por texto, con los nuevos y revolucionarios m\u00f3viles era m\u00e1s f\u00e1cil de esta forma. Sin embargo, desde hace un par de a\u00f1os est\u00e1n creciendo de forma exponencial desde los dispositivos m\u00f3viles. La mejora de esta tecnolog\u00eda para conseguir <strong>transcripciones perfectas<\/strong> de nuestras palabras, sumada a que cada d\u00eda somos m\u00e1s perezosos para realizar las tareas m\u00e1s sencillas, est\u00e1 generando un uso masivo de las b\u00fasquedas por voz.<\/p>\n<p>Como no podr\u00eda ser de otra forma, esto tiene su repercusi\u00f3n en el SEO: debemos optimizar los textos de nuestras webs para nuestras <strong>palabras clave objetivo <\/strong>en&nbsp;las consultas por voz que m\u00e1s realicen los usuarios.<\/p>\n<p>De una cosa podemos estar seguros, no s\u00f3lo en 2018, sino que durante m\u00e1s tiempo&nbsp;esta b\u00fasqueda ser\u00e1 tendencia.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"youtube\"><\/span>YouTube<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Si en algo est\u00e1 de acuerdo la mayor\u00eda de la comunidad online es que cada vez somos m\u00e1s pasivos y nos cuesta m\u00e1s consumir contenido que requiera esfuerzo, por tanto, <strong>el contenido escrito est\u00e1 dejando de ser el principal<\/strong>.<\/p>\n<p><a class=\"lightbox\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/video.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-3300 alignleft\" src=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/video.jpg\" alt=\"youtube\" width=\"232\" height=\"232\"><\/a><\/p>\n<p>El v\u00eddeo, las im\u00e1genes, los gifs, etc. van a jugar un papel cada vez m\u00e1s importante en el posicionamiento org\u00e1nico y van a estar m\u00e1s presentes en las estrategias de todas las marcas.<\/p>\n<p>Los datos est\u00e1n ah\u00ed: el segundo buscador con m\u00e1s tr\u00e1fico en Internet es <strong>YouTube<\/strong>, lo que para muchas empresas es un escaparate potencial donde mostrarse, publicitarse y darse a conocer de una manera diferente.<\/p>\n<p>Aunque creamos que YouTube est\u00e1 en su fase madura y empezar ahora y triunfar es muy dif\u00edcil nos estamos equivocando rotundamente. Hay muchos nichos de mercado que no est\u00e1n trabajados ni optimizados en formato audiovisual y<strong> esta es una gran oportunidad para ganar visibilidad, autoridad de marca <\/strong>y, por lo tanto, m\u00e1s tr\u00e1fico y m\u00e1s negocio.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"google-rich-answers\"><\/span>Google Rich Answers<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Quiz\u00e1 el t\u00e9rmino \u00ab<em><strong>rich answers<\/strong><\/em>\u00bb no te suene mucho, en este caso una imagen vale m\u00e1s que mil palabras porque seguro que has visto esto en el buscador de Google alguna vez:<\/p>\n<figure id=\"attachment_3291\" aria-describedby=\"caption-attachment-3291\" style=\"width: 454px\" class=\"wp-caption aligncenter\"><a class=\"lightbox\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/google-rich-answers.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3291\" src=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/google-rich-answers.jpg\" alt=\"google-rich-answers\" width=\"454\" height=\"395\"><\/a><figcaption id=\"caption-attachment-3291\" class=\"wp-caption-text\">Google Rich Answer<\/figcaption><\/figure>\n<p>Las t\u00e9cnicas tradicionales de SEO implican como resultado un aumento de la visibilidad de las p\u00e1ginas web en los resultados de b\u00fasqueda. Si estos resultados, por cambios que el propio Google realiza, <strong>son reemplazados u ocultos por un nuevo tipo de respuesta (Google Rich Answer) <\/strong>la visibilidad de los resultados anteriores ser\u00e1 necesariamente mucho menor.<\/p>\n<p><strong>Google va a invertir todos sus esfuerzos en responder directamente a la consulta del usuario,<\/strong> es menos probable que el usuario haga clic en otro sitio si el propio buscador ya le est\u00e1 mostrando la respuesta. Esto implica una menor visibilidad en los resultados que hasta ahora, sal\u00edan en primeras posiciones.<\/p>\n<p>Si quieres ampliar informaci\u00f3n sobre este tema y conocer c\u00f3mo poner en pr\u00e1ctica estas t\u00e9cnicas, puedes descargarte la grabaci\u00f3n del webinar <a href=\"https:\/\/www.efor.es\/eventos\/herramientas-para-optimizar-y-monitorizar-tu-seo.html\" target=\"_blank\" rel=\"noopener noreferrer\">Herramientas para optimizar y monitorizar tu SEO<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As\u00ed como en otras \u00e1reas del marketing digital como redes sociales, email marketing o SEM, los cambios y las novedades de este a\u00f1o se pueden detectar con facilidad y est\u00e1n bien definidos, el campo del SEO siempre se ha caracterizado por su \u00abpoca transparencia\u00bb. Los grandes buscadores marcan sus propias reglas c\u00f3mo y cuando quieren [&hellip;]<\/p>\n","protected":false},"author":92,"featured_media":9353,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[7],"tags":[210,221],"class_list":{"0":"post-3282","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-marketing-digital","8":"tag-marketing-digital","9":"tag-seo","10":"entry"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/3282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/users\/92"}],"replies":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/comments?post=3282"}],"version-history":[{"count":0,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/3282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media\/9353"}],"wp:attachment":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media?parent=3282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/categories?post=3282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/tags?post=3282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}