
  
{"id":3694,"date":"2018-06-13T07:54:57","date_gmt":"2018-06-13T05:54:57","guid":{"rendered":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/?p=3694"},"modified":"2024-02-29T11:41:02","modified_gmt":"2024-02-29T10:41:02","slug":"la-excelencia-de-las-organizaciones-son-las-personas-parte-2","status":"publish","type":"post","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\/","title":{"rendered":"La excelencia de las organizaciones son las personas (Parte 2)"},"content":{"rendered":"<p>Tras la publicaci\u00f3n de la <a href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/la-excelencia-de-las-organizaciones-son-las-personas-parte-i\/\" target=\"_blank\" rel=\"noopener\">primera parte de este art\u00edculo<\/a> donde habl\u00e1bamos, entre otras ideas, de innovaci\u00f3n empresarial a trav\u00e9s de las personas, tambi\u00e9n en estos d\u00edas llegaron hasta m\u00ed, a trav\u00e9s de las redes sociales, unas reflexiones de Xavier Marcet, bien interesantes, sobre qu\u00e9 hace que las estrategias de las organizaciones lleguen o no a buen t\u00e9rmino.<\/p>\n<p>Los planteamientos del citado experto nos ponen ante razonamientos como que <strong>las ideas sobre hacia d\u00f3nde queremos ir no se pueden desligar del talento<\/strong> que las debe hacer realidad. Seg\u00fan \u00e9l, las citadas ideas pueden ser relevantes e inspiradoras, pero su impacto depende de quien las haya de ejecutar, de su competencia, su \u00e9tica, su compromiso. Si estas personas, adem\u00e1s de un <em>qu\u00e9<\/em> estrat\u00e9gico, tienen un <em>porqu\u00e9<\/em>, un prop\u00f3sito consistente, a ser posible, alineado con sus propias motivaciones, es mucho m\u00e1s f\u00e1cil que esa estrategia se haga realidad.<\/p>\n<p>Este <strong>binomio estrategia-talento<\/strong> es clave. Lograr que esas personas con talento, esas que dan resultados sistem\u00e1ticamente por encima de la media, se comprometan con los objetivos de la organizaci\u00f3n y asuman con responsabilidad la implantaci\u00f3n de actividades de planes y proyectos es fundamental para que la estrategia no quede en un adorno de estanter\u00eda.<\/p>\n<p>Otro factor del \u00e9xito del logro de la estrategia radica en que \u00e9sta debe funcionar como inspiraci\u00f3n latente, lo que hace que tenga mucho de planificaci\u00f3n, pero tambi\u00e9n una gran carga de <strong>innovaci\u00f3n y flexibilidad.<\/strong> Por ello, los robots, los datos y los algoritmos, nos podr\u00e1n ayudar a\u00a0 preparar las estrategias, pero la diferencia para el \u00e9xito en su ejecuci\u00f3n la pondr\u00e1n las personas.<\/p>\n<p>El dilema que me generan estas ideas es: \u00bfser\u00e1 verdad que ante la incertidumbre y complejidad de nuestro entorno lo que triunfa es una <strong>visi\u00f3n estrat\u00e9gica de futuro y mucho talento<\/strong> para adaptarla a un mundo que cambia aceleradamente? A\u00fan m\u00e1s, \u00bflas ideas, por brillantes que sean, s\u00f3lo nos llevar\u00e1n a la excelencia si se entienden <strong>desde las personas<\/strong> que las moldean, las concretan y las convierten en impacto y en resultados?<\/p>\n<p>En otro orden de cosas, y gracias a la informaci\u00f3n compartida por el <strong>Club Excelencia en Gesti\u00f3n<\/strong>, pude acceder a las aportaciones del admirado Juan Carlos Cubeiro en una publicaci\u00f3n sobre \u201c<em>Liderazgo para transformar las organizaciones<\/em>\u201d. En su art\u00edculo se concentra en observar el liderazgo no como la jefatura tradicional, sino como un tipo muy especial de talento, lo que enfoca como \u201ctalento para influir decisivamente en los dem\u00e1s\u201d, desde la <strong>autoridad moral, <\/strong>desde la<strong> credibilidad, <\/strong>desde el<strong> ejemplo cotidiano<\/strong>.<\/p>\n<p>Nos plantea que la experiencia ha ido demostrando que las organizaciones que no cuentan con un Modelo de Liderazgo bien definido y adaptado a su realidad, que parte de unos valores propios y compartidos que se concretan en una lista corta de comportamientos coherentes con ellos, tienen una rentabilidad de la inversi\u00f3n en formaci\u00f3n y desarrollo en habilidades directivas muy pobre, cercana a tirar el dinero.<\/p>\n<p>En particular, y hablando del impacto del liderazgo, afirma que <strong>hasta el 90% del desarrollo de la organizaci\u00f3n o aprendizaje empresarial depende de la calidad directiva<\/strong>; que la captaci\u00f3n, fidelizaci\u00f3n y compromiso del talento depende en un 70% de la reputaci\u00f3n y ejemplo cotidiano de los l\u00edderes. Incluso llega a plantear que la facturaci\u00f3n y el margen en los resultados se ven influidos entre un 20 y un 30 % por la efectividad en el ejercicio del liderazgo.<\/p>\n<p>El \u201cModelo de \u00c9xito de Liderazgo\u201d que aplica en su empresa se compone de cuatro grandes ejes: <strong>cliente; liderazgo de personas; liderazgo de ideas; resultados<\/strong>. Con una l\u00f3gica muy de Modelos como el de EFQM o el Cuadro de Mando Integral, seg\u00fan la cual el gran arrastrador de resultados clave es la orientaci\u00f3n al cliente; y el de \u00e9sta, el liderazgo de personas. En la base de todo estar\u00eda el <strong>liderazgo de ideas<\/strong> como impulsor de la transformaci\u00f3n de las mismas en soluciones para los clientes, con una orientaci\u00f3n hacia soluciones innovadoras, diferenciadas y conectadas con sus necesidades para ofrecerle una gran experiencia. El liderazgo de personas pasar\u00eda por lograr la colaboraci\u00f3n y el compromiso de todos con el logro de resultados definidos como estrat\u00e9gicos.<\/p>\n<p>El debate a donde me llevan estos enunciados es: \u00bfser\u00e1 fundamental el papel de los responsables como l\u00edderes-mentores del desarrollo de sus colaboradores para marcar la diferencia que permita la supervivencia del proyecto empresarial?, incluso, \u00bfla responsabilidad de los l\u00edderes para lograr el compromiso de sus personas ser\u00e1 uno de los factores m\u00e1s determinantes en su fidelizaci\u00f3n y productividad, en la satisfacci\u00f3n de los clientes, en la rentabilidad y resultados clave de la empresa?<\/p>\n<p>Continuar\u00e1\u2026 si t\u00fa quieres.<\/p>\n<p><em><strong>Art\u00edculo redactado por\u00a0<a href=\"https:\/\/www.linkedin.com\/in\/joseantoniocalvo\/\">Jos\u00e9 Antonio Calvo<\/a>, director de Qualitas, y Natalia Vicente, directora de Consultor\u00eda de ProQuo.\u00a0<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras la publicaci\u00f3n de la primera parte de este art\u00edculo donde habl\u00e1bamos, entre otras ideas, de innovaci\u00f3n empresarial a trav\u00e9s de las personas, tambi\u00e9n en estos d\u00edas llegaron hasta m\u00ed, a trav\u00e9s de las redes sociales, unas reflexiones de Xavier Marcet, bien interesantes, sobre qu\u00e9 hace que las estrategias de las organizaciones lleguen o no [&hellip;]<\/p>\n","protected":false},"author":114,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[83],"tags":[228,211],"class_list":["post-3694","post","type-post","status-publish","format-standard","category-estrategia","tag-excelencia-empresarial","tag-rrhh","entry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Tras la publicaci\u00f3n de la primera parte de este art\u00edculo donde habl\u00e1bamos, entre otras ideas, de innovaci\u00f3n empresarial a trav\u00e9s de las personas, tambi\u00e9n en estos d\u00edas llegaron hasta m\u00ed, a trav\u00e9s de las redes sociales, unas reflexiones de Xavier Marcet, bien interesantes, sobre qu\u00e9 hace que las estrategias de las organizaciones lleguen o no\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Jos\u00e9 Antonio Calvo\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"La Innovaci\u00f3n Necesaria | Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Excelencia empresarial y personas | La Innovaci\u00f3n Necesaria\" \/>\n\t\t<meta property=\"og:description\" content=\"Tras la publicaci\u00f3n de la primera parte de este art\u00edculo donde habl\u00e1bamos, entre otras ideas, de innovaci\u00f3n empresarial a trav\u00e9s de las personas, tambi\u00e9n en estos d\u00edas llegaron hasta m\u00ed, a trav\u00e9s de las redes sociales, unas reflexiones de Xavier Marcet, bien interesantes, sobre qu\u00e9 hace que las estrategias de las organizaciones lleguen o no\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-06-13T05:54:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-02-29T10:41:02+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Excelencia empresarial y personas | La Innovaci\u00f3n Necesaria\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Tras la publicaci\u00f3n de la primera parte de este art\u00edculo donde habl\u00e1bamos, entre otras ideas, de innovaci\u00f3n empresarial a trav\u00e9s de las personas, tambi\u00e9n en estos d\u00edas llegaron hasta m\u00ed, a trav\u00e9s de las redes sociales, unas reflexiones de Xavier Marcet, bien interesantes, sobre qu\u00e9 hace que las estrategias de las organizaciones lleguen o no\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\\\/#article\",\"name\":\"Excelencia empresarial y personas | La Innovaci\\u00f3n Necesaria\",\"headline\":\"La excelencia de las organizaciones son las personas (Parte 2)\",\"author\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/jacalvo_integra\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-integra-blanco.svg\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#articleImage\",\"width\":165,\"height\":38},\"datePublished\":\"2018-06-13T07:54:57+02:00\",\"dateModified\":\"2024-02-29T11:41:02+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\\\/#webpage\"},\"articleSection\":\"Estrategia, excelencia empresarial, rrhh\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/categorias\\\/estrategia\\\/#listItem\",\"name\":\"Estrategia\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/categorias\\\/estrategia\\\/#listItem\",\"position\":2,\"name\":\"Estrategia\",\"item\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/categorias\\\/estrategia\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\\\/#listItem\",\"name\":\"La excelencia de las organizaciones son las personas (Parte 2)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\\\/#listItem\",\"position\":3,\"name\":\"La excelencia de las organizaciones son las personas (Parte 2)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/categorias\\\/estrategia\\\/#listItem\",\"name\":\"Estrategia\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#organization\",\"name\":\"La Innovaci\\u00f3n Necesaria\",\"description\":\"Blog sobre tecnolog\\u00eda, business intelligence, marketing digital, cloud y seguridad.\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-integra-blanco.svg\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\\\/#organizationLogo\",\"width\":165,\"height\":38},\"image\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/jacalvo_integra\\\/#author\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/jacalvo_integra\\\/\",\"name\":\"Jos\\u00e9 Antonio Calvo\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/jacalvo.jpg\",\"width\":96,\"height\":96,\"caption\":\"Jos\\u00e9 Antonio Calvo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\\\/#webpage\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\\\/\",\"name\":\"Excelencia empresarial y personas | La Innovaci\\u00f3n Necesaria\",\"description\":\"Tras la publicaci\\u00f3n de la primera parte de este art\\u00edculo donde habl\\u00e1bamos, entre otras ideas, de innovaci\\u00f3n empresarial a trav\\u00e9s de las personas, tambi\\u00e9n en estos d\\u00edas llegaron hasta m\\u00ed, a trav\\u00e9s de las redes sociales, unas reflexiones de Xavier Marcet, bien interesantes, sobre qu\\u00e9 hace que las estrategias de las organizaciones lleguen o no\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/jacalvo_integra\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/jacalvo_integra\\\/#author\"},\"datePublished\":\"2018-06-13T07:54:57+02:00\",\"dateModified\":\"2024-02-29T11:41:02+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#website\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/\",\"name\":\"La Innovaci\\u00f3n Necesaria\",\"description\":\"Blog sobre tecnolog\\u00eda, business intelligence, marketing digital, cloud y seguridad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Excelencia empresarial y personas | La Innovaci\u00f3n Necesaria","description":"Tras la publicaci\u00f3n de la primera parte de este art\u00edculo donde habl\u00e1bamos, entre otras ideas, de innovaci\u00f3n empresarial a trav\u00e9s de las personas, tambi\u00e9n en estos d\u00edas llegaron hasta m\u00ed, a trav\u00e9s de las redes sociales, unas reflexiones de Xavier Marcet, bien interesantes, sobre qu\u00e9 hace que las estrategias de las organizaciones lleguen o no","canonical_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\/#article","name":"Excelencia empresarial y personas | La Innovaci\u00f3n Necesaria","headline":"La excelencia de las organizaciones son las personas (Parte 2)","author":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/jacalvo_integra\/#author"},"publisher":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#articleImage","width":165,"height":38},"datePublished":"2018-06-13T07:54:57+02:00","dateModified":"2024-02-29T11:41:02+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\/#webpage"},"isPartOf":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\/#webpage"},"articleSection":"Estrategia, excelencia empresarial, rrhh"},{"@type":"BreadcrumbList","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria#listItem","position":1,"name":"Inicio","item":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria","nextItem":{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/estrategia\/#listItem","name":"Estrategia"}},{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/estrategia\/#listItem","position":2,"name":"Estrategia","item":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/estrategia\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\/#listItem","name":"La excelencia de las organizaciones son las personas (Parte 2)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\/#listItem","position":3,"name":"La excelencia de las organizaciones son las personas (Parte 2)","previousItem":{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/estrategia\/#listItem","name":"Estrategia"}}]},{"@type":"Organization","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#organization","name":"La Innovaci\u00f3n Necesaria","description":"Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/","logo":{"@type":"ImageObject","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\/#organizationLogo","width":165,"height":38},"image":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/jacalvo_integra\/#author","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/jacalvo_integra\/","name":"Jos\u00e9 Antonio Calvo","image":{"@type":"ImageObject","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\/#authorImage","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2021\/08\/jacalvo.jpg","width":96,"height":96,"caption":"Jos\u00e9 Antonio Calvo"}},{"@type":"WebPage","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\/#webpage","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\/","name":"Excelencia empresarial y personas | La Innovaci\u00f3n Necesaria","description":"Tras la publicaci\u00f3n de la primera parte de este art\u00edculo donde habl\u00e1bamos, entre otras ideas, de innovaci\u00f3n empresarial a trav\u00e9s de las personas, tambi\u00e9n en estos d\u00edas llegaron hasta m\u00ed, a trav\u00e9s de las redes sociales, unas reflexiones de Xavier Marcet, bien interesantes, sobre qu\u00e9 hace que las estrategias de las organizaciones lleguen o no","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#website"},"breadcrumb":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\/#breadcrumblist"},"author":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/jacalvo_integra\/#author"},"creator":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/jacalvo_integra\/#author"},"datePublished":"2018-06-13T07:54:57+02:00","dateModified":"2024-02-29T11:41:02+01:00"},{"@type":"WebSite","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#website","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/","name":"La Innovaci\u00f3n Necesaria","description":"Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#organization"}}]},"og:locale":"es_ES","og:site_name":"La Innovaci\u00f3n Necesaria | Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.","og:type":"article","og:title":"Excelencia empresarial y personas | La Innovaci\u00f3n Necesaria","og:description":"Tras la publicaci\u00f3n de la primera parte de este art\u00edculo donde habl\u00e1bamos, entre otras ideas, de innovaci\u00f3n empresarial a trav\u00e9s de las personas, tambi\u00e9n en estos d\u00edas llegaron hasta m\u00ed, a trav\u00e9s de las redes sociales, unas reflexiones de Xavier Marcet, bien interesantes, sobre qu\u00e9 hace que las estrategias de las organizaciones lleguen o no","og:url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\/","og:image":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg","og:image:secure_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg","article:published_time":"2018-06-13T05:54:57+00:00","article:modified_time":"2024-02-29T10:41:02+00:00","twitter:card":"summary","twitter:title":"Excelencia empresarial y personas | La Innovaci\u00f3n Necesaria","twitter:description":"Tras la publicaci\u00f3n de la primera parte de este art\u00edculo donde habl\u00e1bamos, entre otras ideas, de innovaci\u00f3n empresarial a trav\u00e9s de las personas, tambi\u00e9n en estos d\u00edas llegaron hasta m\u00ed, a trav\u00e9s de las redes sociales, unas reflexiones de Xavier Marcet, bien interesantes, sobre qu\u00e9 hace que las estrategias de las organizaciones lleguen o no","twitter:image":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg"},"aioseo_meta_data":{"post_id":"3694","title":"Excelencia empresarial y personas | #site_title","description":null,"keywords":[{"label":"excelencia empresarial","value":"excelencia empresarial"},{"label":"rrhh","value":"rrhh"}],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-09-28 14:54:41","updated":"2024-02-29 10:41:02","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/estrategia\/\" title=\"Estrategia\">Estrategia<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa excelencia de las organizaciones son las personas (Parte 2)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria"},{"label":"Estrategia","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/estrategia\/"},{"label":"La excelencia de las organizaciones son las personas (Parte 2)","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/la-excelencia-de-las-organizaciones-son-las-personas-parte-2\/"}],"_links":{"self":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/3694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/users\/114"}],"replies":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/comments?post=3694"}],"version-history":[{"count":1,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/3694\/revisions"}],"predecessor-version":[{"id":11687,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/3694\/revisions\/11687"}],"wp:attachment":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media?parent=3694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/categories?post=3694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/tags?post=3694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}