
  
{"id":3845,"date":"2018-08-23T08:48:33","date_gmt":"2018-08-23T06:48:33","guid":{"rendered":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/?p=3845"},"modified":"2023-12-26T17:50:38","modified_gmt":"2023-12-26T16:50:38","slug":"por-que-y-como-debes-gestionar-la-experiencia-de-tus-clientes","status":"publish","type":"post","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/por-que-y-como-debes-gestionar-la-experiencia-de-tus-clientes\/","title":{"rendered":"Por qu\u00e9 y c\u00f3mo debes gestionar la experiencia de tus clientes"},"content":{"rendered":"<p><em>\u2018\u2018El 80% de las empresas creen que entregan una experiencia superior a sus clientes, pero s\u00f3lo el 8% de sus clientes est\u00e1n de acuerdo\u2019\u2019<\/em><br \/>\nBain &amp; Co. (2007), Bain Customer Led Growth Diagnostic Questionnaire.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice de contenidos <\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #3acdef;color:#3acdef\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #3acdef;color:#3acdef\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/por-que-y-como-debes-gestionar-la-experiencia-de-tus-clientes\/#el-interes-de-la-experiencia-del-cliente\" >El inter\u00e9s de la experiencia del cliente<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/por-que-y-como-debes-gestionar-la-experiencia-de-tus-clientes\/#del-buyer-persona-al-customer-experience-management-cem\" >Del Buyer Persona al Customer Experience Management (CEM)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/por-que-y-como-debes-gestionar-la-experiencia-de-tus-clientes\/#la-excelencia-en-la-experiencia\" >La excelencia en la experiencia<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"el-interes-de-la-experiencia-del-cliente\"><\/span>El inter\u00e9s de la experiencia del cliente<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>En un momento en el que los productos y servicios se est\u00e1n <em>comoditizando<\/em>, no podr\u00eda darle un mejor consejo a una empresa que no\u00a0sea invertir en mejorar la relaci\u00f3n con sus clientes.\u00a0Apenas existe diferenciaci\u00f3n de productos o, al menos, los clientes los perciben como id\u00e9nticos y no son capaces de distinguirlos, por lo que se vuelve inminente la necesidad de <strong>innovar a lo largo de todo el proceso de compra<\/strong>. Y ello tiene sentido, ya que \u00e9ste comienza antes incluso de llegar a la tienda y termina mucho despu\u00e9s, viviendo el cliente a lo largo de todo su viaje numerosas experiencias.<\/p>\n<p>Existen multitud de definiciones o, mejor dicho, aproximaciones al concepto de \u2018\u2018experiencia de cliente\u2019\u2019. Yo, por mi parte, no me atrevo a dar una, pero s\u00ed te puedo contar las notas clave de este t\u00e9rmino:<\/p>\n<ol>\n<li><strong>La Customer Experience (CX)<\/strong> implica pasar de<strong> \u2018\u2018conocer al cliente\u2019\u2019 <\/strong>a<strong> \u2018\u2018entender al cliente\u2019\u2019<\/strong>. Se trata de gestionar sus emociones una vez ha tenido contacto con nuestra marca o empresa.<\/li>\n<li>Para conseguir <strong>experiencias diferenciales<\/strong> es imprescindible tener en cuenta el punto de partida; para poder dise\u00f1ar e implementar una CX positiva hay que analizar las necesidades y objetivos del cliente. De esta manera, podr\u00e1 establecerse una estrategia para <strong>fortalecer las emociones positivas y minimizar las negativas<\/strong>.<\/li>\n<li>Son experiencias tanto las positivas como las negativas y el cliente recordar\u00e1 aquellas realmente intensas. Dejando a un lado que la mejor experiencia ser\u00eda la que no necesita de servicio de atenci\u00f3n al cliente, \u00e9ste recordar\u00e1 esa vez en la que tuvo un problema y la empresa lo solucion\u00f3 con rapidez. Si bien es cierto, tambi\u00e9n recordar\u00e1 su mala experiencia con un empleado de la tienda f\u00edsica.<\/li>\n<\/ol>\n<p>A d\u00eda de hoy, hay clientes de todos los tipos por lo que ser\u00e1 necesario <strong>construir su mapa de experiencia <\/strong>a trav\u00e9s de su viaje particular (<strong>customer journey<\/strong>). Sin embargo, si hay algo que es com\u00fan a todos ellos es que la experiencia solo es efectiva si la recuerdan y, por lo general, hay dos momentos que siempre recordar\u00e1: el <strong>final de la experiencia<\/strong> y el <strong>pico emocional<\/strong> en el que afloraron emociones de gran intensidad. Es decir, el cliente no va a recordar los momentos intermedios o, al menos, no van a ser relevantes a la hora de establecer su experiencia.<\/p>\n<p>La generaci\u00f3n de la experiencia viene determinada por diferentes <strong>puntos de contacto<\/strong>, ya sean canales o momentos de interacci\u00f3n. Ser\u00e1n <strong>experience providers<\/strong> los elementos t\u00e1cticos que cobran importancia al contacto con el cliente. No solo se considerar\u00e1n proveedores de experiencia los diferentes canales (call center, email, tienda f\u00edsica, redes sociales, etc) sino tambi\u00e9n, las comunicaciones de la empresa (logo, identidad corporativa), el aspecto del producto (dise\u00f1o, envase, existencia de marca), el sitio web, el personal y los entornos espaciales. De todos ellos va a depender la <strong>percepci\u00f3n<\/strong> que tenga el cliente del producto o empresa y generar\u00e1 el resultado de la experiencia: las emociones.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"del-buyer-persona-al-customer-experience-management-cem\"><\/span>Del Buyer Persona al Customer Experience Management (CEM)<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Antes de empezar a idear la estrategia que mejore la experiencia de tus clientes es necesario conocerlos. Como se ha dicho, el punto de partida est\u00e1 en el contexto, en las necesidades y deseos de los clientes.<\/p>\n<p>Cada empresa es un mundo y cada cliente, un universo. Es por eso que el primer paso en la CEM es identificar qui\u00e9nes son los clientes. Un proceso de segmentaci\u00f3n puede resultar interesante como investigaci\u00f3n exploratoria pero lo que ser\u00e1 realmente \u00fatil a la hora de tomar decisiones son los <a href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/el-marketing-tradicional-ha-muerto-bienvenido-a-los-buyer-persona\/\"><strong>Buyer Personas<\/strong><\/a>.<\/p>\n<p><a class=\"lightbox\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/buyer-persona.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-3849\" src=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/buyer-persona.png\" alt=\"buyer persona\" width=\"316\" height=\"475\" \/><\/a><\/p>\n<p>La potencialidad de esta herramienta es infinita ya que podr\u00e1s tomar las decisiones comerciales, de dise\u00f1o de producto y de marketing pensando en una persona en concreto. Una persona que, de hecho, representa a un conjunto de tus clientes con todo detalle.<\/p>\n<p>Una vez definida nuestros Buyer personas es hora de identificar su recorrido durante el proceso de compra: el <strong>customer journey<\/strong>. Comprende todas las fases en las que el cliente va a tener contacto o no con la empresa, antes, durante y despu\u00e9s\u00a0del proceso de compra.\u00a0En esta experiencia del cliente\u00a0ser\u00e1n identificados los diferentes <strong>touch points<\/strong> e interacciones del cliente con la marca, las acciones que realiza el cliente, las comunicaciones de la empresa y las emociones. Con ello, tendremos una foto completa del recorrido del cliente al relacionarse con el producto o servicio ofrecido por nuestra empresa.<\/p>\n<p>En este viaje, ser\u00e1 clave identificar aquellos puntos de contacto que se configuran como momentos de la verdad. Estos son \u00fanicos y tienen un enorme poder, siendo capaces de generar picos emocionales determinantes.<\/p>\n<p>Como estamos hablando de <strong>CEM<\/strong>, es decir, de la gesti\u00f3n completa de la experiencia de cliente, hay que vincular todo este trabajo de definici\u00f3n con los procesos internos de la empresa. La fusi\u00f3n del customer journey y el mapa de procesos es lo que se denomina como <strong>Blueprint<\/strong>. Permite orientar todo el trabajo de la empresa a la vivencia experiencial del cliente. Es, sin duda, el complemento perfecto para un CEM perfecto.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"la-excelencia-en-la-experiencia\"><\/span>La excelencia en la experiencia<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>En definitiva, en el proceso de CEM se trata de conocer al cliente, pero no solo sus caracter\u00edsticas objetivas y visibles sino empatizar con \u00e9l. Ser consciente de sus necesidades y, sobre todo, saber c\u00f3mo se siente respecto a ellas y las soluciones que le ofrecemos.<\/p>\n<p>La excelencia en la experiencia va a depender de todo el trabajo previo de definici\u00f3n, puesto que constituye los cimientos de la gesti\u00f3n de la experiencia del cliente. Adem\u00e1s\u00a0requiere conectar el viaje del cliente con el trabajo interno de la empresa.<\/p>\n<p>Pero la excelencia en la experiencia no se consigue regalando por regalar, sorprendiendo por sorprender. Consiste en dar un valor diferencial al cliente que impacte en la vivencia que tiene con la empresa o marca, haciendo que el cliente nos recuerde de forma positiva.<\/p>\n<p>Para m\u00e1s info, no dude en visitar <a href=\"https:\/\/www.qualitas.es\" target=\"\u201d_blank\u201d\" rel=\"noopener noreferrer\">Qualitas<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2018\u2018El 80% de las empresas creen que entregan una experiencia superior a sus clientes, pero s\u00f3lo el 8% de sus clientes est\u00e1n de acuerdo\u2019\u2019 Bain &amp; Co. (2007), Bain Customer Led Growth Diagnostic Questionnaire. El inter\u00e9s de la experiencia del cliente En un momento en el que los productos y servicios se est\u00e1n comoditizando, no [&hellip;]<\/p>\n","protected":false},"author":59,"featured_media":9611,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[83],"tags":[],"class_list":{"0":"post-3845","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-estrategia","8":"entry"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/3845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/comments?post=3845"}],"version-history":[{"count":0,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/3845\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media\/9611"}],"wp:attachment":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media?parent=3845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/categories?post=3845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/tags?post=3845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}