
  
{"id":4901,"date":"2019-11-07T11:35:41","date_gmt":"2019-11-07T10:35:41","guid":{"rendered":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/?p=4901"},"modified":"2023-12-26T18:02:36","modified_gmt":"2023-12-26T17:02:36","slug":"integracion-la-clave-de-microsoft-power-platform","status":"publish","type":"post","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/integracion-la-clave-de-microsoft-power-platform\/","title":{"rendered":"Integraci\u00f3n, la clave de Microsoft Power Platform"},"content":{"rendered":"<p>Hoy vamos a comentar la plataforma de Microsoft \u201cMicrosoft Power Platform\u201d que en el momento actual engloba <strong>PowerApps,\u00a0Power Automate (Flow) y PowerBI. <\/strong>Tres herramientas que \u201cempoderan\u201d al usuario\/empresas con el tratamiento de sus datos y su an\u00e1lisis.<\/p>\n<p><strong>Microsoft PowerBI<\/strong> es la herramienta de an\u00e1lisis de datos bajo el t\u00e9rmino de \u00ab<strong>Business Intelligence<\/strong>\u201d y que es espec\u00edfica para esa labor, adem\u00e1s de ser la herramienta de an\u00e1lisis de uso que usan sus aplicaciones hermanas para su control estad\u00edstico de descargas y uso: <strong>Power Automate\u00a0<\/strong>y PowerApps. Las otras dos herramientas casi siempre van a ir unidas ya que nos ayudan a conectar dos sistemas y pasar datos entre ellos transform\u00e1ndolos o convirti\u00e9ndolos, para lo cual necesitaremos crear un \u201cflujo\u201d de trabajo que integre ambos mundos y dise\u00f1ar un interface de usuario para ello.<\/p>\n<p><strong>Microsoft Power Automate<\/strong> y <strong>PowerApps<\/strong> son dos herramientas \u201cde programaci\u00f3n\u201d, aunque no es una programaci\u00f3n tradicional como puede ser Visual Studio o Xamarin, ya que est\u00e1n pensadas para ayudar en procesos que solucionen problemas concretos en las organizaciones como, por ejemplo:<\/p>\n<ul>\n<li><strong>Migrar documentos<\/strong> de Dropbox a OneDrive con todos los metadatos de los ficheros reorganizando la informaci\u00f3n mediante el dise\u00f1o de un flujo.<\/li>\n<li>Crear un <strong>flujo completo de aprobaci\u00f3n<\/strong> de documentaci\u00f3n en la intranet en el que intervengan varios departamentos y dise\u00f1ar el flujo mediante el diagramador visual: Microsoft Visio o la propia interface web de <strong>Power Automate<\/strong>.<\/li>\n<li><strong>Registrar las visitas comerciales<\/strong> en una BBDD Oracle, adjuntando coordenadas GPS del cliente y fotos del pedido<\/li>\n<li>Crear una aplicaci\u00f3n para <strong>registrar incidencias <\/strong>con la c\u00e1mara de un m\u00f3vil, registrarlas en una intranet con SharePoint y hacer seguimiento de estas incidencias mediante un Teams para el equipo de trabajo que incluya un Planner para el seguimiento de los estados de estas incidencias adem\u00e1s de una librer\u00eda de documentos relacionados.<\/li>\n<li>Crear una APP, para que mediante una Tablet en <strong>recepci\u00f3n de una consulta m\u00e9dica<\/strong> se registre el consentimiento de los pacientes a la protecci\u00f3n de datos, con su firma manuscrita y a\u00f1ada esta informaci\u00f3n a la ficha ya existente en otros sistemas del paciente.<\/li>\n<\/ul>\n<p>Como podemos ver, son procesos concretos, que pueden convivir con otros sistemas de gesti\u00f3n m\u00e1s complejos y que tiene el m\u00f3vil como herramienta m\u00e1s operativa para realizar esta labor.<\/p>\n<p>Otra ventaja de estos sistemas es que nos permiten interactuar con otros softwares que no son de Microsoft.<\/p>\n<ul>\n<li><strong>Fuentes de datos:<\/strong> Oracle, MySQL, Postgre, Dropbox, OneDrive, Box, FTP, etc<\/li>\n<li><strong>Conectores con software espec\u00edfico de terceros:<\/strong> Jira, Asana, Facebook, Twitter, Instagram, MailChimp, Adobe, Gmail, Google Docs., Google Maps, Bitly, BaseCamp2,&#8230; (m\u00e1s de 250 conectores actualmente)<\/li>\n<li>Por supuesto,<strong> todo el ecosistema de Office365:<\/strong> SharePoint, OneDrive, Teams, Planner, Office, OneNote, Outlook, Dynamics, Forms, LinkedIn, etc.<\/li>\n<li>Y si esto no es suficiente, es posible desarrollar nuestros propios conectores mediante <strong>webservices con la API disponible<\/strong>.<\/li>\n<\/ul>\n<p>En este <a href=\"https:\/\/flow.microsoft.com\/es-es\/connectors\/\" target=\"\u201d_blank\u201d\" rel=\"noopener noreferrer\">link<\/a> podemos ver todos los conectores disponibles actualmente.<\/p>\n<p>Como podemos ver los or\u00edgenes de datos suelen ser servicios en la nube, pero tambi\u00e9n es posible conectar con servidores en nuestro propio hosting local mediante Microsoft Gateway, con lo que podremos, por ejemplo, crear aplicaciones m\u00f3viles que accedan a un servidor SQL Server local en la organizaci\u00f3n.<\/p>\n<p>PowerApps no est\u00e1 pensado para crear un sistema de gesti\u00f3n completo, no es el objetivo de esta herramienta. Aunque no hay limitaci\u00f3n en este sentido, hay herramientas del propio Microsoft para hacer estos sistemas como por ejemplo Xamarin, que permite realizar aplicaciones m\u00f3viles completas para Android e iOS con un solo c\u00f3digo fuente.<\/p>\n<p>Microsoft tambi\u00e9n est\u00e1 integrando en PowerApps herramientas de IA \u201c<strong>Inteligencia Artificial<\/strong>\u201d con <strong>AI Builder<\/strong> y en estos momentos disponemos de cuatro modelos de IA que podemos integrar en cualquier aplicaci\u00f3n m\u00f3vil: Reconocimiento formularios, reconocimiento de objetos en im\u00e1genes, predicci\u00f3n de cosas a ocurrir, an\u00e1lisis de textos; y el cat\u00e1logo se supone que seguir\u00e1 creciendo con nuevos modelos de IA. Para su integraci\u00f3n no es necesario escribir ni una sola l\u00ednea de c\u00f3digo ya que cuenta con plantillas preconfiguradas para cada modelo y un proceso guiado.<\/p>\n<p><a class=\"lightbox\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/integracion-la-clave-de-microsoft-power-platform\/ai-builder\/\" rel=\"attachment wp-att-4915\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-4915\" src=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/AI-Builder.png\" alt=\"AI Builder\" width=\"300\" height=\"188\" \/><\/a><\/p>\n<h3><strong>Aclaraciones \/ Preguntas<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p><strong>\u00bfPuede usar <strong>Power Automate<\/strong> y PowerApps alguien sin ning\u00fan conocimiento de programaci\u00f3n?:<\/strong> NO, pero si se ha programado anteriormente en alg\u00fan otro lenguaje orientado a objetos el aprendizaje es muy corto adem\u00e1s de tener en Internet multitud de ejemplos ya realizados que pueden servir de tutoriales para crear nuevas aplicaciones. La programaci\u00f3n y funciones usadas en ambos sistemas son muy similares a las de Microsoft Excel por lo que tambi\u00e9n es una herramienta orienta a analistas de negocio en la organizaci\u00f3n.<\/p>\n<p><strong>\u00bfSon Gratis?:<\/strong> No. Se pueden comprar planes mensuales\/anuales para el uso de cualquiera de las herramientas por separado y vienen incluidas en la mayor\u00eda de los planes de Office365 (aunque limitadas en las funcionalidades \u201cPremium\u201d). Por ejemplo, se puede contratar Microsoft <strong>Power Automate<\/strong> durante los meses que se necesite para hacer una migraci\u00f3n de datos entre dos sistemas.<\/p>\n<p><strong>\u00bfC\u00f3mo se publican las aplicaciones m\u00f3viles para que las tengan disponibles los usuarios?: <\/strong>una ventaja sustancial es que no hay que pasar por las tiendas de aplicaciones de Google y Apple, simplemente se descarga en el dispositivo Microsoft Power Automate y\/o Microsoft PowerApps y ejecutando \u00fanicamente esta aplicaci\u00f3n el usuario ver\u00e1 todas las aplicaciones m\u00f3viles o flujos a los que le haya dado acceso la empresa. Todo ello securizado mediante los sistemas de autentificaci\u00f3n de <strong>Microsoft Offie365<\/strong>.<\/p>\n<p><a class=\"lightbox\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/integracion-la-clave-de-microsoft-power-platform\/power-platform\/\" rel=\"attachment wp-att-4916\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-4916\" src=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/power-platform.png\" alt=\"power-platform\" width=\"300\" height=\"188\" \/><\/a><a class=\"lightbox\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/integracion-la-clave-de-microsoft-power-platform\/microsoft-power-platform-2\/\" rel=\"attachment wp-att-4917\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-4917\" src=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/microsoft-power-platform.png\" alt=\"microsoft-power-platform\" width=\"300\" height=\"188\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a class=\"lightbox\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/integracion-la-clave-de-microsoft-power-platform\/measure-act-automate\/\" rel=\"attachment wp-att-4919\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-4919\" src=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/measure-act-automate.png\" alt=\"measure-act-automate\" width=\"300\" height=\"196\" \/><\/a><a class=\"lightbox\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/integracion-la-clave-de-microsoft-power-platform\/my-analytics\/\" rel=\"attachment wp-att-4920\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-4920\" src=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/my-analytics.png\" alt=\"my-analytics\" width=\"300\" height=\"189\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>Art\u00edculo redactado por Jos\u00e9 Antonio Perna<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy vamos a comentar la plataforma de Microsoft \u201cMicrosoft Power Platform\u201d que en el momento actual engloba PowerApps,\u00a0Power Automate (Flow) y PowerBI. Tres herramientas que \u201cempoderan\u201d al usuario\/empresas con el tratamiento de sus datos y su an\u00e1lisis. Microsoft PowerBI es la herramienta de an\u00e1lisis de datos bajo el t\u00e9rmino de \u00abBusiness Intelligence\u201d y que es [&hellip;]<\/p>\n","protected":false},"author":92,"featured_media":9967,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[365],"tags":[],"class_list":{"0":"post-4901","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tecnologia-para-la-empresa","8":"entry"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/4901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/users\/92"}],"replies":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/comments?post=4901"}],"version-history":[{"count":0,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/4901\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media\/9967"}],"wp:attachment":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media?parent=4901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/categories?post=4901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/tags?post=4901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}