
  
{"id":5354,"date":"2020-04-27T10:34:48","date_gmt":"2020-04-27T08:34:48","guid":{"rendered":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/?p=5354"},"modified":"2023-12-26T18:05:52","modified_gmt":"2023-12-26T17:05:52","slug":"como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19","status":"publish","type":"post","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/","title":{"rendered":"C\u00f3mo las apps nos ayudan a luchar contra el Covid-19"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Desde Integra queremos transmitir nuestro m\u00e1s sincero agradecimiento a nuestros profesionales sanitarios, as\u00ed como al resto de profesionales que est\u00e1n luchando en primera l\u00ednea, sin ellos esta batalla estar\u00eda perdida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presente art\u00edculo pretende describir c\u00f3mo las apps est\u00e1n ayudando en la lucha contra este virus. Los pa\u00edses l\u00edderes en desarrollo tecnol\u00f3gico las utilizan para intentar poner freno a la r\u00e1pida expansi\u00f3n del este virus, aplicaciones m\u00f3viles (apps) y chatbots, inteligencia artificial, drones y robots, ayudan a ello.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Describiremos las funcionalidades de algunas aplicaciones m\u00f3viles (apps), que est\u00e1n lanzadas, en proceso de lanzamiento o de mejora. Es dif\u00edcil encontrar una persona que no disponga de un m\u00f3vil, este se ha convertido en una herramienta que nos acompa\u00f1a en todo momento y por \u00e9l recibimos gran parte de nuestra informaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas apps nos informan, nos ayudan a prevenir, a conocer la evoluci\u00f3n de la pandemia y permiten planificar acciones gubernamentales. En diferentes foros se trabaja en identificar c\u00f3mo ser\u00e1 el fin del confinamiento, algunos expertos hablan de que estas apps van a ser imprescindibles en esa fase.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como ejemplo describimos las funcionalidades de 4 de ellas: \u201cTraceTogether\u201d en Singapur, \u201cCovid-19.eus\u201d en el Pa\u00eds Vasco, \u00abCoronaMadrid\u00bb en la comunidad de Madrid y \u201cStopCovid19Cat\u201d en Catalu\u00f1a\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Singapur<\/strong> es uno de los pa\u00edses con menos casos de infectados por el Covid-19, el gobierno lanz\u00f3 una aplicaci\u00f3n, \u201cTraceTogether\u201d, que, por medio del Bluetooh convierte el m\u00f3vil en una especie de radar que contacta con los tel\u00e9fonos de personas cercanas cuando pasas a su lado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si te paras a hablar con una persona a menos de un metro, la app de tu tel\u00e9fono se comunica de forma cifrada con el de la otra persona y viceversa, tu m\u00f3vil recoge informaci\u00f3n del resto de m\u00f3viles y almacena esta informaci\u00f3n, si tu das positivo, puedes ceder la informaci\u00f3n al Gobierno para que pueda avisar a las personas con las que has tenido contacto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El Gobierno Vasco<\/strong>, ha desarrollado Covid-19.eus, una app cuyo objetivo es tejer una red ciudadana que ayude en la contenci\u00f3n del coronavirus, contribuyendo a su prevenci\u00f3n, detecci\u00f3n y seguimiento. La herramienta usa el mismo modelo de seguimiento de la OMS y el Centro Europeo para el control de Enfermedades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Covid-19.eus tiene un triple objetivo:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Prevenci\u00f3n<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Cada persona se la puede descargar, a\u00f1adir su estado de salud mediante un autodiagn\u00f3stico y puede agregar a su c\u00edrculo cercano tanto familiar, amistad o laboral\/educativo. As\u00ed todas las personas est\u00e1n interconectadas, reciben las recomendaciones habituales, hacen el seguimiento de su salud y ven el estado de las dem\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Mayor seguimiento de posibles casos en los domicilios<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Permitir\u00e1 al Departamento de Salud y a Osakidetza un mayor conocimiento y seguimiento, siempre de forma an\u00f3nima, de las personas con s\u00edntomas que est\u00e1n en sus domicilios. Profesionales sanitarios de apoyo dar\u00e1n cobertura diaria a las personas en cuarentena con afectaci\u00f3n leve o moderada<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. Concentraci\u00f3n de casos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Servir\u00e1 de refuerzo para el trabajo de los equipos de epidemiolog\u00eda, que podr\u00e1n ubicar d\u00f3nde est\u00e1n localizados los casos y realizar as\u00ed, si fuera necesario, intervenciones m\u00e1s individualizadas de diagn\u00f3stico y seguimiento en zonas de alta transmisi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La<strong> Comunidad de Madrid<\/strong> ha lanzado una app de autodiagn\u00f3stico para COVID-19 para m\u00f3viles, a la que ha llamado \u00abCoronaMadrid\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Comunidad de Madrid ha lanzado la \u2018app\u2019 sobre el coronavirus (COVID-19) que facilita una auto-evaluaci\u00f3n a los ciudadanos y sus posibles dolencias desde sus casas a trav\u00e9s del tel\u00e9fono m\u00f3vil: \u201cCoronamadrid\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La aplicaci\u00f3n m\u00f3vil se suma a la web <a href=\"http:\/\/www.coronamadrid.com\">www.coronamadrid.com<\/a>, estrenada cuatro d\u00edas antes por el Gobierno regional, visitada ya por m\u00e1s de 2 millones de internautas y que ha realizado 200.000 auto-evaluaciones del coronavirus. Esta app est\u00e1 disponible de forma gratuita para los sistemas iOS y Android.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>StopCovid19Cat<\/strong> es una nueva aplicaci\u00f3n para dispositivos m\u00f3viles que har\u00e1 un seguimiento de la evoluci\u00f3n de la pandemia del coronavirus en<strong> Catalu\u00f1a<\/strong>. La nueva herramienta tecnol\u00f3gica contribuir\u00e1 a detectar la enfermedad, hacer un seguimiento de los pacientes, ver c\u00f3mo evoluciona la pandemia y favorecer la toma de mejores decisiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La app ayuda a las personas que presentan alg\u00fan s\u00edntoma espec\u00edfico de Covid 19 (fiebre, tos, dificultad respiratoria, malestar general, etc.) por medio de un sencillo test, que proporcionar\u00e1 la informaci\u00f3n necesaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El sistema de salud recibir\u00e1 esta informaci\u00f3n, la aplicaci\u00f3n permitir\u00e1 hacer un seguimiento en el tiempo de los pacientes, con lo cual se obtendr\u00e1 un conocimiento mayor sobre la evoluci\u00f3n de la pandemia de forma localizada por poblaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esperemos que este peque\u00f1o resumen nos ayude a identificar como la tecnolog\u00eda nos ayuda y ayudar\u00e1 en nuestro d\u00eda a d\u00eda. Las apps han venido para quedarse, que ser\u00e1n cr\u00edticas cuando salgamos de nuestras casas tras esta etapa de confinamiento y que la tecnolog\u00eda aporta valor en el control y lucha contra esta pandemia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pensemos igualmente en como las apps pueden ayudar a nuestras empresas, el estado de alarma ha hecho que nos recluyamos en nuestras casas, al salir seguro que nuestra forma de relacionarnos cambiar\u00e1 dado que estamos teniendo un aprendizaje r\u00e1pido en el uso de medios electr\u00f3nicos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desde Integra queremos transmitir nuestro m\u00e1s sincero agradecimiento a nuestros profesionales sanitarios, as\u00ed como al resto de profesionales que est\u00e1n luchando en primera l\u00ednea, sin ellos esta batalla estar\u00eda perdida. El presente art\u00edculo pretende describir c\u00f3mo las apps est\u00e1n ayudando en la lucha contra este virus. Los pa\u00edses l\u00edderes en desarrollo tecnol\u00f3gico las utilizan para [&hellip;]<\/p>\n","protected":false},"author":95,"featured_media":10132,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[365],"tags":[],"class_list":["post-5354","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tecnologia-para-la-empresa","entry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Estas apps nos informan, nos ayudan a prevenir, a conocer la evoluci\u00f3n de la pandemia y permiten planificar acciones gubernamentales.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Luis Sarasa\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"La Innovaci\u00f3n Necesaria | Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"C\u00f3mo las apps nos ayudan a luchar contra el Covid-19 | La Innovaci\u00f3n Necesaria\" \/>\n\t\t<meta property=\"og:description\" content=\"Estas apps nos informan, nos ayudan a prevenir, a conocer la evoluci\u00f3n de la pandemia y permiten planificar acciones gubernamentales.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-04-27T08:34:48+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-12-26T17:05:52+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"C\u00f3mo las apps nos ayudan a luchar contra el Covid-19 | La Innovaci\u00f3n Necesaria\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Estas apps nos informan, nos ayudan a prevenir, a conocer la evoluci\u00f3n de la pandemia y permiten planificar acciones gubernamentales.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\\\/#article\",\"name\":\"C\\u00f3mo las apps nos ayudan a luchar contra el Covid-19 | La Innovaci\\u00f3n Necesaria\",\"headline\":\"C\\u00f3mo las apps nos ayudan a luchar contra el Covid-19\",\"author\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/lsarasa_integra\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/app-frente-al-coronavirus.png\",\"width\":1349,\"height\":200},\"datePublished\":\"2020-04-27T10:34:48+02:00\",\"dateModified\":\"2023-12-26T18:05:52+01:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\\\/#webpage\"},\"articleSection\":\"Tecnolog\\u00eda para la empresa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/categorias\\\/tecnologia-para-la-empresa\\\/#listItem\",\"name\":\"Tecnolog\\u00eda para la empresa\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/categorias\\\/tecnologia-para-la-empresa\\\/#listItem\",\"position\":2,\"name\":\"Tecnolog\\u00eda para la empresa\",\"item\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/categorias\\\/tecnologia-para-la-empresa\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\\\/#listItem\",\"name\":\"C\\u00f3mo las apps nos ayudan a luchar contra el Covid-19\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\\\/#listItem\",\"position\":3,\"name\":\"C\\u00f3mo las apps nos ayudan a luchar contra el Covid-19\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/categorias\\\/tecnologia-para-la-empresa\\\/#listItem\",\"name\":\"Tecnolog\\u00eda para la empresa\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#organization\",\"name\":\"La Innovaci\\u00f3n Necesaria\",\"description\":\"Blog sobre tecnolog\\u00eda, business intelligence, marketing digital, cloud y seguridad.\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo-integra-blanco.svg\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\\\/#organizationLogo\",\"width\":165,\"height\":38},\"image\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/lsarasa_integra\\\/#author\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/lsarasa_integra\\\/\",\"name\":\"Luis Sarasa\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\\\/#authorImage\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/luis.png\",\"width\":96,\"height\":96,\"caption\":\"Luis Sarasa\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\\\/#webpage\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\\\/\",\"name\":\"C\\u00f3mo las apps nos ayudan a luchar contra el Covid-19 | La Innovaci\\u00f3n Necesaria\",\"description\":\"Estas apps nos informan, nos ayudan a prevenir, a conocer la evoluci\\u00f3n de la pandemia y permiten planificar acciones gubernamentales.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/lsarasa_integra\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/author\\\/lsarasa_integra\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/app-frente-al-coronavirus.png\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\\\/#mainImage\",\"width\":1349,\"height\":200},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\\\/#mainImage\"},\"datePublished\":\"2020-04-27T10:34:48+02:00\",\"dateModified\":\"2023-12-26T18:05:52+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#website\",\"url\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/\",\"name\":\"La Innovaci\\u00f3n Necesaria\",\"description\":\"Blog sobre tecnolog\\u00eda, business intelligence, marketing digital, cloud y seguridad.\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.integratecnologia.es\\\/la-innovacion-necesaria\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"C\u00f3mo las apps nos ayudan a luchar contra el Covid-19 | La Innovaci\u00f3n Necesaria","description":"Estas apps nos informan, nos ayudan a prevenir, a conocer la evoluci\u00f3n de la pandemia y permiten planificar acciones gubernamentales.","canonical_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/#article","name":"C\u00f3mo las apps nos ayudan a luchar contra el Covid-19 | La Innovaci\u00f3n Necesaria","headline":"C\u00f3mo las apps nos ayudan a luchar contra el Covid-19","author":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/lsarasa_integra\/#author"},"publisher":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/app-frente-al-coronavirus.png","width":1349,"height":200},"datePublished":"2020-04-27T10:34:48+02:00","dateModified":"2023-12-26T18:05:52+01:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/#webpage"},"isPartOf":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/#webpage"},"articleSection":"Tecnolog\u00eda para la empresa"},{"@type":"BreadcrumbList","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria#listItem","position":1,"name":"Inicio","item":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria","nextItem":{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/tecnologia-para-la-empresa\/#listItem","name":"Tecnolog\u00eda para la empresa"}},{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/tecnologia-para-la-empresa\/#listItem","position":2,"name":"Tecnolog\u00eda para la empresa","item":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/tecnologia-para-la-empresa\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/#listItem","name":"C\u00f3mo las apps nos ayudan a luchar contra el Covid-19"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/#listItem","position":3,"name":"C\u00f3mo las apps nos ayudan a luchar contra el Covid-19","previousItem":{"@type":"ListItem","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/tecnologia-para-la-empresa\/#listItem","name":"Tecnolog\u00eda para la empresa"}}]},{"@type":"Organization","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#organization","name":"La Innovaci\u00f3n Necesaria","description":"Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/","logo":{"@type":"ImageObject","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/#organizationLogo","width":165,"height":38},"image":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/lsarasa_integra\/#author","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/lsarasa_integra\/","name":"Luis Sarasa","image":{"@type":"ImageObject","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/#authorImage","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2020\/04\/luis.png","width":96,"height":96,"caption":"Luis Sarasa"}},{"@type":"WebPage","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/#webpage","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/","name":"C\u00f3mo las apps nos ayudan a luchar contra el Covid-19 | La Innovaci\u00f3n Necesaria","description":"Estas apps nos informan, nos ayudan a prevenir, a conocer la evoluci\u00f3n de la pandemia y permiten planificar acciones gubernamentales.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#website"},"breadcrumb":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/#breadcrumblist"},"author":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/lsarasa_integra\/#author"},"creator":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/lsarasa_integra\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/app-frente-al-coronavirus.png","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/#mainImage","width":1349,"height":200},"primaryImageOfPage":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/#mainImage"},"datePublished":"2020-04-27T10:34:48+02:00","dateModified":"2023-12-26T18:05:52+01:00"},{"@type":"WebSite","@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#website","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/","name":"La Innovaci\u00f3n Necesaria","description":"Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/#organization"}}]},"og:locale":"es_ES","og:site_name":"La Innovaci\u00f3n Necesaria | Blog sobre tecnolog\u00eda, business intelligence, marketing digital, cloud y seguridad.","og:type":"article","og:title":"C\u00f3mo las apps nos ayudan a luchar contra el Covid-19 | La Innovaci\u00f3n Necesaria","og:description":"Estas apps nos informan, nos ayudan a prevenir, a conocer la evoluci\u00f3n de la pandemia y permiten planificar acciones gubernamentales.","og:url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/","og:image":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg","og:image:secure_url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg","article:published_time":"2020-04-27T08:34:48+00:00","article:modified_time":"2023-12-26T17:05:52+00:00","twitter:card":"summary","twitter:title":"C\u00f3mo las apps nos ayudan a luchar contra el Covid-19 | La Innovaci\u00f3n Necesaria","twitter:description":"Estas apps nos informan, nos ayudan a prevenir, a conocer la evoluci\u00f3n de la pandemia y permiten planificar acciones gubernamentales.","twitter:image":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/01\/logo-integra-blanco.svg"},"aioseo_meta_data":{"post_id":"5354","title":"C\u00f3mo las apps nos ayudan a luchar contra el Covid-19 | #site_title","description":"Estas apps nos informan, nos ayudan a prevenir, a conocer la evoluci\u00f3n de la pandemia y permiten planificar acciones gubernamentales.","keywords":[{"label":"app","value":"app"}],"keyphrases":null,"primary_term":null,"canonical_url":"","og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-09-28 14:46:28","updated":"2022-09-17 00:28:46","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/tecnologia-para-la-empresa\/\" title=\"Tecnolog\u00eda para la empresa\">Tecnolog\u00eda para la empresa<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tC\u00f3mo las apps nos ayudan a luchar contra el Covid-19\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria"},{"label":"Tecnolog\u00eda para la empresa","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/categorias\/tecnologia-para-la-empresa\/"},{"label":"C\u00f3mo las apps nos ayudan a luchar contra el Covid-19","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/como-las-apps-nos-ayudan-a-luchar-contra-el-covid-19\/"}],"_links":{"self":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/5354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/users\/95"}],"replies":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/comments?post=5354"}],"version-history":[{"count":0,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/5354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media\/10132"}],"wp:attachment":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media?parent=5354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/categories?post=5354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/tags?post=5354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}