
  
{"id":6430,"date":"2018-11-02T06:25:31","date_gmt":"2018-11-02T05:25:31","guid":{"rendered":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/?p=6430"},"modified":"2023-12-26T18:25:27","modified_gmt":"2023-12-26T17:25:27","slug":"proyectos-de-customer-analytics-beneficios-barreras-y-como-implementarlos","status":"publish","type":"post","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/proyectos-de-customer-analytics-beneficios-barreras-y-como-implementarlos\/","title":{"rendered":"Proyectos de Customer Analytics: beneficios, barreras y c\u00f3mo implementarlos"},"content":{"rendered":"<p>En la actualidad, observamos que muchas empresas tienen dudas a la hora de realizar un proyecto de an\u00e1lisis de datos. Surgen dudas y cuesta mucho, en un inicio, demostrar el valor y el impacto que los resultados y las acciones que se plantean producir\u00e1n en la empresa. A continuaci\u00f3n, respondemos varias preguntas \u00bfqu\u00e9 es un proyecto de Customer Analytics? \u00bfQu\u00e9 barreras existen? \u00bfQu\u00e9 beneficios aporta? \u00bfC\u00f3mo lo llevamos a cabo?<\/p>\n<p>Las organizaciones est\u00e1n viviendo una profunda transformaci\u00f3n, no s\u00f3lo desde la perspectiva de los sistemas de informaci\u00f3n, la digitalizaci\u00f3n, tecnolog\u00edas o de la necesidad de lidiar con las nuevas estructuras en red, sino tambi\u00e9n en la adopci\u00f3n de la idea que el dato est\u00e1 desempe\u00f1ando un rol cada vez m\u00e1s determinante para la generaci\u00f3n de ventajas competitivas.<\/p>\n<p>Un cambio de dimensi\u00f3n mundial que afecta a toda la sociedad y, por consecuencia, al cliente. Este hecho conlleva fuertes inversiones para las empresas en infraestructura tecnol\u00f3gica y de procesos.<\/p>\n<p>Una estrategia global centrada en el cliente debe conocer a ciencia cierta qu\u00e9 valor aporta la empresa al cliente y qu\u00e9 valor genera \u00e9l a la compa\u00f1\u00eda.\u00a0 La anal\u00edtica de cliente no es \u00fanicamente una tarea de marketing, sino que resulta vital para el dise\u00f1o de productos, desarrollo de servicios y otras \u00e1reas que se necesitan en la empresa.<\/p>\n<p>Barreras en la implementaci\u00f3n de un proyecto de Customer Analytics<\/p>\n<p>Tanto en el momento de iniciar un proyecto de\u00a0<em>Customer Analytics<\/em>\u00a0como en el desarrollo de \u00e9ste, pueden surgir diferentes dificultades. Un estudio titulado\u00a0<a href=\"https:\/\/www.ca.com\/content\/dam\/ca\/us\/files\/industry-analyst-report\/the-state-of-big-data-infrastructure.pdf\"><strong><em>The State of Big Data Infrastructure: Benchmarking Global Big Data Users to Drive Future Performance<\/em><\/strong>,<\/a>\u00a0recoge las cinco mayores barreras a superar en la implementaci\u00f3n de un proyecto de\u00a0<em>Customer Analytics<\/em>\u00a0en\u00a0<a href=\"https:\/\/www.socialnautas.es\/?s=big+data\">Big Data<\/a>: infraestructura existente insuficiente (32%), complejidad de la organizaci\u00f3n (27%), preocupaci\u00f3n por la seguridad y cumplimiento de normativas (26%), falta de presupuesto y\/o recursos (25%), y falta de visibilidad de la informaci\u00f3n y los procesos (25%). Otras vicisitudes que podemos encontrarnos son:<\/p>\n<p>\u2013\u00a0 La organizaci\u00f3n no comprende el concepto de cliente.<\/p>\n<p>\u2013\u00a0 Insuficiente apoyo por parte de la Direcci\u00f3n en la iniciativa.<\/p>\n<p>\u2013\u00a0 Falta de liderazgo y gesti\u00f3n de proyecto.<\/p>\n<p>\u2013\u00a0 Dificultad en identificar y cuantificar el retorno de inversi\u00f3n y el valor generado para la organizaci\u00f3n y el cliente<\/p>\n<p>\u2013\u00a0 La calidad de datos en la organizaci\u00f3n es insuficiente para abordar un proceso de inteligencia de clientes.<\/p>\n<p>\u2013\u00a0 Dificultad para integrar los recursos existentes de Business Intelligence, Datawarehouse o las aplicaciones disponibles en la organizaci\u00f3n.<\/p>\n<p>\u2013\u00a0 Falta de personal cualificado o capacidad para formar al existente.<\/p>\n<p>\u2013\u00a0 Dificultad para relacionar e integrar el resultado de los an\u00e1lisis con los distintos procesos del negocio.<\/p>\n<p>\u2013\u00a0 Inmadurez de las organizaciones en integrar la presencia en redes sociales y los datos derivados con los datos disponibles de un cliente en los canales tradicionales.<\/p>\n<p>\u2013\u00a0 Par\u00e1lisis en la toma de decisiones por un sobre an\u00e1lisis de los datos.<\/p>\n<p>&nbsp;<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice de contenidos <\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #3acdef;color:#3acdef\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #3acdef;color:#3acdef\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/proyectos-de-customer-analytics-beneficios-barreras-y-como-implementarlos\/#beneficios-de-un-proyecto-de-customer-analytics\" >Beneficios de un proyecto de Customer Analytics<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/proyectos-de-customer-analytics-beneficios-barreras-y-como-implementarlos\/#fase-comprension-del-negocio\" >Fase Comprensi\u00f3n del negocio<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/proyectos-de-customer-analytics-beneficios-barreras-y-como-implementarlos\/#fase-comprension-de-los-datos\" >Fase Comprensi\u00f3n de los datos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/proyectos-de-customer-analytics-beneficios-barreras-y-como-implementarlos\/#fase-de-preparacion-de-los-datos\" >Fase de preparaci\u00f3n de los datos\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/proyectos-de-customer-analytics-beneficios-barreras-y-como-implementarlos\/#fase-de-modelado\" >Fase de modelado<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/proyectos-de-customer-analytics-beneficios-barreras-y-como-implementarlos\/#evaluacion-del-modelo\" >Evaluaci\u00f3n del modelo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/proyectos-de-customer-analytics-beneficios-barreras-y-como-implementarlos\/#determinacion-de-fases-futuras\" >Determinaci\u00f3n de fases futuras<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"beneficios-de-un-proyecto-de-customer-analytics\"><\/span>Beneficios de un proyecto de Customer Analytics<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Seg\u00fan\u00a0<a href=\"https:\/\/www.mckinsey.com\/business-functions\/marketing-and-sales\/our-insights\/five-facts-how-customer-analytics-boosts-corporate-performance\">Mckinsey Datamatics,<\/a>\u00a0en t\u00e9rminos globales, los principales beneficios son:<\/p>\n<ul>\n<li><strong>Incremento del 126% en las opciones de mejorar a la competencia en cuanto a los beneficios.<\/strong><\/li>\n<li><strong>Incremento del 131% en las opciones de mejorar a la competencia en las ventas.<\/strong><\/li>\n<li><strong>Incremento del 132% en las opciones de mejorar a la competencia en el ROI.<\/strong><\/li>\n<\/ul>\n<p>Al margen de estos beneficios, existen otros que podr\u00edamos categorizar en tangibles e intangibles. Destacan los siguientes:<\/p>\n<p>Tangibles:<\/p>\n<p>\u2013\u00a0 Incrementar el valor para la organizaci\u00f3n desplegando estrategias orientadas a incrementar el C<em>ustomer Lifetime Value<\/em>\u00a0para cada cliente.<\/p>\n<p>\u2013\u00a0 Incrementar el valor para el cliente focalizado en incrementar su propuesta de valor y su satisfacci\u00f3n.<\/p>\n<p>\u2013\u00a0 Creaci\u00f3n de nuevos productos basados en las preferencias de los clientes.<\/p>\n<p>\u2013\u00a0 Identificar los paquetes de productos que satisfacen las necesidades de los clientes.<\/p>\n<p>\u2013\u00a0 Incrementar la efectividad de las acciones de marketing generando m\u00e1s ingresos por acci\u00f3n.<\/p>\n<p>\u2013 Mejor retenci\u00f3n de clientes.<\/p>\n<p>\u2013\u00a0 Revisar las estrategias de precio.<\/p>\n<p>\u2013\u00a0 Reducir el tiempo y costes vinculados a la toma de decisiones<\/p>\n<p>\u2013\u00a0 Reducir el riesgo asociado al cliente al identificar perfiles por impago o fraude.<\/p>\n<p>\u2013\u00a0 Mejorar la productividad de la fuerza de venta a partir de la optimizaci\u00f3n de los programas de fidelizaci\u00f3n.<\/p>\n<p>\u2013 Anticiparse a las necesidades del cliente.<\/p>\n<p>Intangibles:<\/p>\n<p>\u2013\u00a0 Aportar conocimiento y herramientas a la direcci\u00f3n para la toma de decisiones sobre los clientes, el mercado y la competencia.<\/p>\n<p>\u2013\u00a0 Detectar cambios en el mercado y adquirir la habilidad para reaccionar a los mismos con rapidez, gracias al conocimiento.<\/p>\n<p>\u2013\u00a0 Capacitar a la organizaci\u00f3n para la creaci\u00f3n de experiencias de cliente mucho mejores que reporten lealtad a la marca.<\/p>\n<p>\u2013\u00a0 Posibilitar la visi\u00f3n 360\u00ba del cliente al poder analizar los datos generados en todos los canales (online, offline).<\/p>\n<p>Hay que evitar dedicar tiempo y recursos a investigar preguntas incorrectas. Una fase cr\u00edtica es realizar las preguntas de negocio correctas.<\/p>\n<p>C\u00f3mo llevar a cabo un proyecto de Customer Analytics<\/p>\n<h3><span class=\"ez-toc-section\" id=\"fase-comprension-del-negocio\"><\/span><strong>Fase Comprensi\u00f3n del negocio<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Tener una visi\u00f3n cristalina del negocio y cu\u00e1les son los objetivos del mismo es vital. Hay que evitar dedicar tiempo y recursos a investigar preguntas incorrectas. Se elaborar\u00e1 un estudio de la situaci\u00f3n actual del negocio respecto de los objetivos definidos. Analizaremos la disponibilidad de recursos, costes, tiempos y detectaremos riesgos. En cuanto a los criterios de \u00e9xito de los objetivos, estos pueden ser de tipo cualitativo, o de tipo cuantitativo, por ejemplo, el n\u00famero de detecciones de abandono o la interacci\u00f3n de clientes ante una campa\u00f1a publicitaria.<\/p>\n<p><strong>\u00a0 \u00a0\u00a0 \u2013 Fijar el objetivo estrat\u00e9gico de negocio<\/strong><\/p>\n<p><strong>\u00a0 \u00a0\u00a0 \u2013 Hacer las preguntas de negocio correctas<\/strong><\/p>\n<p><strong>\u00a0 \u00a0\u00a0 \u2013 Focalizarnos en las preguntas de negocio y en los resultados que queremos conseguir<\/strong><\/p>\n<h3><span class=\"ez-toc-section\" id=\"fase-comprension-de-los-datos\"><\/span><strong>Fase Comprensi\u00f3n de los datos<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Familiarizarse con los datos siempre es importante para explotar al m\u00e1ximo \u00abtodo lo que nos susurran\u00bb, saber de d\u00f3nde provienen,\u00a0 cu\u00e1l es su estructura, en qu\u00e9 condiciones nos llegan, sus propiedades\u2026\u00a0<a href=\"https:\/\/www.socialnautas.es\/big-data-privacidad-etica-y-el-valor-de-los-datos\/\">Esta es una fase cr\u00edtica para asegurar la calidad y \u00e9tica de los datos<\/a>.\u00a0\u00a0<strong>Se verificar\u00e1 la consistencia<\/strong>\u00a0de los valores individuales de los campos,\u00a0<strong>la cantidad y distribuci\u00f3n de los valores nulos<\/strong>, los cuales pueden constituirse en ruido para el proceso. As\u00ed aseguraremos la\u00a0<a href=\"https:\/\/es.wikipedia.org\/wiki\/Completitud_(l%C3%B3gica)\">completitud<\/a>\u00a0y correcci\u00f3n de los datos. Es importante en esta fase conocer el proceso del acr\u00f3nimo ETL (Extracci\u00f3n Transformaci\u00f3n y Carga) lo cu\u00e1l explica muy bien los subprocesos asociados.<\/p>\n<p><strong>\u00a0 \u00a0 \u00a0 \u2013 Primero analizaremos el comportamiento de los clientes extrayendo en los siguientes datos:<\/strong><\/p>\n<ul>\n<li>CRM de la empresa o base de datos propia.<\/li>\n<li>Datos offline: llamadas, visitas a tienda, compras realizadas en tiendas, Wifi Analytics\u2026<\/li>\n<li>Visitas, ventas realizadas, recurrencia, carrito medio, utilizaci\u00f3n de promociones\u2026<\/li>\n<li>Email Marketing. Horas y tasas de apertura de los correos, clics, compras asociadas\u2026<\/li>\n<li>Interacciones, zonas geogr\u00e1ficas\u2026<\/li>\n<li>Accesos, interacciones\u2026<\/li>\n<li>Canales sociales. Datos de Facebook, Instagram, Twitter, etc.<\/li>\n<\/ul>\n<p><strong>\u00a0 \u00a0\u00a0 \u2013 Segmentaci\u00f3n de mercado<\/strong><\/p>\n<p>Se trata de agrupar segmentos afines de clientes que\u00a0compartan patrones comunes, lo que nos permitir\u00e1 dise\u00f1ar campa\u00f1as espec\u00edficas para ellos. La mayor especificidad de los grupos, determinar\u00e1 mayo personalizaci\u00f3n en nuestras campa\u00f1as de:<\/p>\n<ul>\n<li>Fidelizaci\u00f3n. Sobre todo de nuestros clientes m\u00e1s rentables, aumentando tambi\u00e9n la frecuencia de compra.<\/li>\n<li>Reactivaci\u00f3n. De los clientes pasivos.<\/li>\n<li>Empujando a la compra de productos que han adquirido otros usuarios del mismo segmento.<\/li>\n<li>Para hacer crecer el ticket medio.<\/li>\n<\/ul>\n<h3><span class=\"ez-toc-section\" id=\"fase-de-preparacion-de-los-datos\"><\/span><strong>Fase de preparaci\u00f3n de los datos\u00a0<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La finalidad de esta fase es disponer, tras la extracci\u00f3n de todos los datos, de aquellos sobre los que se aplicar\u00e1n los modelos.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"fase-de-modelado\"><\/span><strong>Fase de modelado<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Se debe dise\u00f1ar un m\u00e9todo de evaluaci\u00f3n de los modelos que permita determinar su \u00abgrado de bondad\u00bb que depender\u00e1n de las caracter\u00edsticas de los datos. Existen varios modelos: de tabla, jer\u00e1rquico, de red, esquema de estrella\u2026<\/p>\n<h3><span class=\"ez-toc-section\" id=\"evaluacion-del-modelo\"><\/span><strong>Evaluaci\u00f3n del modelo<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>El objetivo de un proyecto de\u00a0<em>Customer Analytics<\/em>\u00a0no es crear los modelos, sino analizar los descubrimientos,\u00a0 decisivos para alcanzar los objetivos de negocio.<\/p>\n<p>Se probar\u00e1 el modelo en entornos de prueba para certificar de que el posterior proceso se realiza satisfactoriamente y para asegurarnos que el modelo dise\u00f1ado puede dar respuesta a los objetivos de negocio.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"determinacion-de-fases-futuras\"><\/span><strong>Determinaci\u00f3n de fases futuras<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La anal\u00edtica predictiva utiliza datos hist\u00f3ricos y actuales para predecir situaciones futuras. Ser\u00eda el\u00a0aspecto m\u00e1s avanzado del\u00a0<em>Customer Analytics<\/em>, ya que implica algoritmos relativamente complejos para construir los modelos predictivos. Si se considera utilizar\u00a0<em>machine learning<\/em>\u00a0para automatizar, mediante distintos algoritmos, la identificaci\u00f3n de patrones o tendencias que se \u201cocultan\u201d en los datos, resultar\u00e1 muy importante no s\u00f3lo la elecci\u00f3n del algoritmo m\u00e1s adecuado, sino tambi\u00e9n el hecho de disponer de un gran volumen de datos de suficiente calidad<\/p>\n<p>Los proyectos de<em>\u00a0Customer Analytics<\/em>\u00a0son proyectos complejos y todo un reto, pero que sin duda, reportar\u00e1n resultados a corto, medio y largo plazo a la compa\u00f1\u00eda. Adem\u00e1s, son un primer paso para llevar a la empresa a otro nivel y seguir la senda de numerosas empresas de \u00e9xito que operan bajo un modelo\u00a0<em>data driven.\u00a0<\/em><a href=\"https:\/\/www.integratecnologia.es\/quieres-saber-mas-sobre-nuestros-servicios\">Cons\u00faltanos<\/a> si sientes curiosidad por los proyectos de este tipo o te encantar\u00eda poder implementar uno en tu empresa.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la actualidad, observamos que muchas empresas tienen dudas a la hora de realizar un proyecto de an\u00e1lisis de datos. Surgen dudas y cuesta mucho, en un inicio, demostrar el valor y el impacto que los resultados y las acciones que se plantean producir\u00e1n en la empresa. A continuaci\u00f3n, respondemos varias preguntas \u00bfqu\u00e9 es un [&hellip;]<\/p>\n","protected":false},"author":92,"featured_media":10809,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[7],"tags":[],"class_list":{"0":"post-6430","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-marketing-digital","8":"entry"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/6430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/users\/92"}],"replies":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/comments?post=6430"}],"version-history":[{"count":0,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/6430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media\/10809"}],"wp:attachment":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media?parent=6430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/categories?post=6430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/tags?post=6430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}