
  
{"id":7021,"date":"2022-06-02T07:57:14","date_gmt":"2022-06-02T05:57:14","guid":{"rendered":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/?p=7021"},"modified":"2023-12-26T18:37:37","modified_gmt":"2023-12-26T17:37:37","slug":"ya-tenemos-crm-la-cualificacion-de-oportunidades","status":"publish","type":"post","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/ya-tenemos-crm-la-cualificacion-de-oportunidades\/","title":{"rendered":"\u00a1Ya tenemos CRM! La cualificaci\u00f3n de oportunidades"},"content":{"rendered":"<p>La cualificaci\u00f3n de las oportunidades en nuestro CRM es esencial para <strong>dirigir nuestras acciones de marketing al p\u00fablico correcto<\/strong> y no desperdiciar el trabajo del equipo. Llevar a cabo una correcta <strong>evaluaci\u00f3n de la calidad<\/strong> de nuestra base de datos nos dar\u00e1 la <strong>visi\u00f3n completa<\/strong> de la calidad de nuestra base de datos y del alcance real de nuestras estrategias para aplicar las herramientas adecuadas y cumplir con nuestro plan comercial.<\/p>\n<blockquote><p>\u201cLa oportunidad debe ser cualificada y dimensionada por el equipo adecuado\u00bb<\/p><\/blockquote>\n<p><a class=\"lightbox\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/OPP-ABBIERTA.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7024 aligncenter\" src=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/OPP-ABBIERTA.jpg\" alt=\"\" width=\"410\" height=\"197\" \/><\/a><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice de contenidos <\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #3acdef;color:#3acdef\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #3acdef;color:#3acdef\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/ya-tenemos-crm-la-cualificacion-de-oportunidades\/#etapas-de-la-fase-de-cualificacion\" >Etapas de la fase de cualificaci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/ya-tenemos-crm-la-cualificacion-de-oportunidades\/#define-%e2%80%9camigs%e2%80%9d-para-ejecutar-la-cualificacion\" >Define \u201camig@s\u201d para ejecutar la cualificaci\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/ya-tenemos-crm-la-cualificacion-de-oportunidades\/#%c2%bfcuando-pongo-foco\" >\u00bfCu\u00e1ndo pongo foco?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/ya-tenemos-crm-la-cualificacion-de-oportunidades\/#criterios-en-la-fase-de-cualificacion\" >Criterios en la fase de cualificaci\u00f3n<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"etapas-de-la-fase-de-cualificacion\"><\/span>Etapas de la fase de cualificaci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La fase de cualificaci\u00f3n comienza una vez se ha pre-cualificado la oportunidad, quedando dimensionados esfuerzos necesarios en forma de equipos que van a trabajar en la propuesta de colaboraci\u00f3n, tanto el interno como el del cliente.<\/p>\n<p>Tomando este punto de partida, el objetivo final de la fase es dejar preparada y definida la oportunidad de cara a trabajar su presentaci\u00f3n ante cliente.<\/p>\n<p>Para llegar hasta este objetivo, se suceden una serie de reuniones e interacciones internas y con cliente, en la que ir desarrollando los diferentes escenarios que van a definir el alcance final de la oportunidad. Estas reuniones pueden tener diferentes naturalezas<strong>:<\/strong><\/p>\n<p><strong>Internas <\/strong><\/p>\n<ul>\n<li>Preparaci\u00f3n interna de entornos y otras herramientas a utilizar.<\/li>\n<li>Reuniones internas de definici\u00f3n de alcance.<\/li>\n<li>Desarrollo de la soluci\u00f3n t\u00e9cnica.<\/li>\n<li>Reuniones y desarrollos creativas<\/li>\n<li>Reuniones con fabricantes.<\/li>\n<li>Reuniones con otros departamentos de la compa\u00f1\u00eda.<\/li>\n<\/ul>\n<p><strong>Con cliente \/ fabricante <\/strong><\/p>\n<ul>\n<li>Toma de requisitos.<\/li>\n<li>Demos de producto.<\/li>\n<li>Prestaciones parciales con cliente.<\/li>\n<li>Reuniones con fabricantes.<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"define-%e2%80%9camigs%e2%80%9d-para-ejecutar-la-cualificacion\"><\/span>Define \u201camig@s\u201d para ejecutar la cualificaci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p><span style=\"font-size: 16px;\"><a href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/?s=CRM\">Mi grupo de amig@s<\/a> para la fase de cualificaci\u00f3n lo van a conformar principalmente las personas que tienen conocimientos necesarios para dimensionar correctamente el esfuerzo y dar una planificaci\u00f3n aproximada.<\/span><\/p>\n<ul>\n<li>Jefes de \u00c1rea<\/li>\n<li>Directores Departamento<\/li>\n<li>Consultores\/Expertos<\/li>\n<li>Alianzas Externas<\/li>\n<li>Fabricantes<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"%c2%bfcuando-pongo-foco\"><\/span>\u00bfCu\u00e1ndo pongo foco?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La <strong>buena noticia<\/strong> es que la <a href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/ya-tenemos-crm-la-apertura-de-oportunidades\/\"><strong>fase Apertura<\/strong><\/a> est\u00e1 funcionando muy bien y un gran volumen de oportunidades nuevas est\u00e1n pasando a la <strong>fase<\/strong> <strong>de<\/strong> <strong>cualificaci\u00f3n<\/strong>.<a class=\"lightbox\" href=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/funnel-fase-apertura.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-7023 alignright\" src=\"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2023\/12\/funnel-fase-apertura.png\" alt=\"\" width=\"199\" height=\"131\" \/><\/a><\/p>\n<p>La mala noticia es que las oportunidades a cualificar se est\u00e1n acumulando y tenemos que poner <strong>foco en cualificar oportunidades<\/strong>.<\/p>\n<p>Posiblemente es la fase que m\u00e1s <strong>trabajo conjunto y coordinado requiere: <\/strong>Planificar las agendas de \u201ctod@s l@s amig@s\u201d que van a intervenir en las diferentes cualificaciones de las propuestas, personal interno y personal externo a la organizaci\u00f3n.<\/p>\n<p>Durante esta fase, se busca una soluci\u00f3n global a la problem\u00e1tica presentada, se dimensiona operativa y econ\u00f3micamente. Por tanto, se dejan preparados todos los aspectos que intervienen en la soluci\u00f3n y que conforman la propuesta, a la que se aplica el formato de presentaci\u00f3n que se haya decidido. El formato de la presentaci\u00f3n es importante para crear coherencia y homogeneidad en las ofertas, en l\u00ednea con la imagen corporativa.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"criterios-en-la-fase-de-cualificacion\"><\/span>Criterios en la fase de cualificaci\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Los criterios pueden cambiar dependiendo del sector o actividad de la empresa o incluso por objetivos, pero los principales criterios para poner foco en la fase de cualificaci\u00f3n habitualmente son:<\/p>\n<ul>\n<li><strong>Poco volumen de oportunidades en cierre<\/strong>: Suelen provocar que aceleremos <em>artificial e interesadamente<\/em> oportunidades cualificadas.<\/li>\n<li><strong>Periodos de bajo volumen de trabajo \u201coperativo\u201d<\/strong>: Aprovechar estos momentos para acelerar oportunidades por parte de \u201camig@s\u201d, normalmente dedicados a los procesos productivos, operativos o similares. Cualificar siempre ayudar\u00e1 a generar negocio y \u00a1acelerar el trabajo futuro!<\/li>\n<li><strong>Detecci\u00f3n de <em>Bottleneck<\/em><\/strong>: Cuando se detecta un volumen significativo de oportunidades que est\u00e1n <strong>en fase cualificaci\u00f3n<\/strong> desde hace mucho tiempo y se han quedado estancadas.<\/li>\n<li><strong>Periodos de alto volumen de trabajo en una alianza externa en concreto<\/strong>: Proyectos comunes que se encuentran en un periodo de alta actividad comercial. La cualificaci\u00f3n ayudar\u00e1 a reorganizar la informaci\u00f3n y tener una visi\u00f3n amplia y detallada para tomar decisiones meditadas y coherentes a la estrategia conjunta en la colaboraci\u00f3n.<\/li>\n<li><strong>Periodos de alto volumen de trabajo en tipos concretos de proyectos<\/strong>: Subvenciones puntuales para algunos tipos de proyectos. Con la cualificaci\u00f3n podremos decidir con fundamento d\u00f3nde invertir este flujo de l\u00edquido y tener mejores resultados que desembocar\u00e1n en beneficios a medio plazo.<\/li>\n<\/ul>\n<p>El siguiente paso es <strong>\u201cDefinir las bases de nuestra Fase de Presentaci\u00f3n\u201d<\/strong>, sigue la serie de \u00a1Ya tenemos CRM! Para estar al tanto de todo el proceso de venta y si necesitas cualquier consulta personalizada <a href=\"https:\/\/www.integratecnologia.es\/quieres-saber-mas-sobre-nuestros-servicios\">no dudes en contactarnos<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cualificaci\u00f3n de las oportunidades en nuestro CRM es esencial para dirigir nuestras acciones de marketing al p\u00fablico correcto y no desperdiciar el trabajo del equipo. Llevar a cabo una correcta evaluaci\u00f3n de la calidad de nuestra base de datos nos dar\u00e1 la visi\u00f3n completa de la calidad de nuestra base de datos y del [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":11083,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[305],"tags":[],"class_list":{"0":"post-7021","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-software-de-gestion","8":"entry"},"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/7021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/comments?post=7021"}],"version-history":[{"count":0,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/posts\/7021\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media\/11083"}],"wp:attachment":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/media?parent=7021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/categories?post=7021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/tags?post=7021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}