
  
{"id":12,"name":"Mar\u00eda Mart\u00ednez","url":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/Maria_M\/","description":"Apasionada de las nuevas tecnolog\u00edas. Soy de las que piensa que Internet es el mejor invento del siglo y de las que se alegra cuando hay Wi-Fi. En casa me llaman friki, pero pienso que no es para tanto. Diplomada en Turismo y amante de los viajes. Comenc\u00e9 con el marketing online como un complemento a mis trabajos en el mundo tur\u00edstico y se ha convertido en lo que me entusiasma cada d\u00eda. Actualmente trabajo en el departamento de Marketing Digital de EFOR. Pienso y confirmo que con esfuerzo y ganas se puede conseguir cualquier cosa que te propongas.","link":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/author\/maria_m\/","slug":"maria_m","avatar_urls":{"24":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/02\/maria-75x75.jpg","48":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/02\/maria-75x75.jpg","96":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-content\/uploads\/2024\/02\/maria-150x150.jpg"},"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/users\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.integratecnologia.es\/la-innovacion-necesaria\/wp-json\/wp\/v2\/users"}]}}